{"id":501,"date":"2022-09-30T19:30:44","date_gmt":"2022-09-30T23:30:44","guid":{"rendered":"http:\/\/he.legal\/he\/?p=501"},"modified":"2022-10-05T15:37:57","modified_gmt":"2022-10-05T19:37:57","slug":"ley-organica-del-ministerio-publico","status":"publish","type":"post","link":"http:\/\/he.legal\/he\/ley-organica-del-ministerio-publico\/","title":{"rendered":"LEY ORG\u00c1NICA DEL MINISTERIO P\u00daBLICO"},"content":{"rendered":"\n<p><strong>T\u00edtulo I<br>Disposiciones Generales<\/strong><\/p>\n\n\n\n<p><strong>Cap\u00edtulo I<br>Objeto de la Ley y Naturaleza Jur\u00eddica del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1. Objeto de la Ley.<\/strong> La presente Ley tiene por objeto regular la organizaci\u00f3n administrativa y funcional del Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>Art\u00edculo 2. Naturaleza jur\u00eddica del Ministerio P\u00fablico.<\/strong> El Ministerio P\u00fablico es un \u00f3rgano del Poder Ciudadano que tiene por objetivo actuar en representaci\u00f3n del inter\u00e9s general y es responsable del respeto a los derechos y garant\u00edas constitucionales a fin de preservar el Estado, democr\u00e1tico y social de derecho y de justicia.<\/p>\n\n\n\n<p><strong>Cap\u00edtulo II<br>Principios Rectores<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 3. Legalidad.<\/strong> El Ministerio P\u00fablico se regir\u00e1 por lo establecido en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, las leyes nacionales y sus reglamentos, y tratados internacionales en materia de derechos humanos, suscritos y ratificados por la Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 4. Independencia y autonom\u00eda.<\/strong> El Ministerio P\u00fablico es independiente de todos los Poderes P\u00fablicos, y goza de autonom\u00eda funcional, organizativa, presupuestaria, financiera y administrativa. En consecuencia, no podr\u00e1 ser impedido ni coartado en el ejercicio de sus atribuciones por ninguna autoridad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 5. Deber de colaboraci\u00f3n.<\/strong> Los Poderes P\u00fablicos, las entidades p\u00fablicas y privadas y los ciudadanos y ciudadanas deber\u00e1n colaborar con el Ministerio P\u00fablico cuando sean requeridos para ello.<\/p>\n\n\n\n<p><strong>Art\u00edculo 6. Unidad de Criterio y Actuaci\u00f3n.<\/strong> El Ministerio P\u00fablico es \u00fanico e indivisible. Estar\u00e1 a cargo y bajo la conducci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica o del que haga sus veces, quien ejercer\u00e1 sus atribuciones de manera directa o a trav\u00e9s de los funcionarios o funcionarias debidamente facultados o facultadas mediante delegaci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 7. Representaci\u00f3n judicial.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica, sin perjuicio de las atribuciones de la Procuradur\u00eda General de la Rep\u00fablica, podr\u00e1 designar representantes ante cualquier tribunal, para sostener los derechos e intereses del Ministerio P\u00fablico en los juicios, seg\u00fan corresponda.<\/p>\n\n\n\n<p><strong>Art\u00edculo 8. \u00d3rgano jerarquizado.<\/strong> El Ministerio P\u00fablico es un \u00f3rgano jerarquizado. El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, ejerce la representaci\u00f3n, direcci\u00f3n, control y disciplina; su autoridad se extiende a todos los funcionarios y funcionarias del Ministerio P\u00fablico. Sin embargo, la representaci\u00f3n, direcci\u00f3n y control podr\u00e1n ser ejercidas por intermedio de los funcionarios o funcionarias que sean nombrados seg\u00fan el dise\u00f1o organizacional del Ministerio P\u00fablico.<\/p>\n\n\n\n<p>Sin perjuicio de formular las observaciones que consideren convenientes, los o las fiscales estar\u00e1n obligados a acatar las instrucciones y directrices que imparta el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, o mediante los funcionarios o funcionarias jer\u00e1rquicamente correspondientes para la realizaci\u00f3n de la investigaci\u00f3n penal o para el ejercicio de la representaci\u00f3n del Ministerio P\u00fablico ante los tribunales, sean \u00e9stos de competencia ordinaria o especial, y deber\u00e1n informar a \u00e9ste o \u00e9sta, o a los funcionarios o funcionarias designados o designadas seg\u00fan la jerarqu\u00eda, sobre el estado en que se encuentren todos los procesos cuando sean requeridos. En todo caso, el Ministerio P\u00fablico dispondr\u00e1 de un sistema de informaci\u00f3n para el seguimiento de las causas.<\/p>\n\n\n\n<p><strong>Art\u00edculo 9. Control de gesti\u00f3n.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, as\u00ed como los funcionarios o funcionarias que sean nombrados o nombradas seg\u00fan el dise\u00f1o organizacional del Ministerio P\u00fablico para ejercer la representaci\u00f3n, direcci\u00f3n y disciplina, dentro del \u00e1mbito de las atribuciones que les confieren las leyes, ejercer\u00e1n el control de gesti\u00f3n de los funcionarios o funcionarias bajo su dependencia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 10. Objetividad.<\/strong> Los fiscales o las fiscales del Ministerio P\u00fablico adecuar\u00e1n sus actos a criterios de objetividad, procurando siempre la correcta interpretaci\u00f3n de la ley con preeminencia de la justicia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 11. Transparencia.<\/strong> Las atribuciones del Ministerio P\u00fablico se ejercer\u00e1n con transparencia, de manera que permitan y promuevan la publicidad y el conocimiento de los procedimientos, contenidos y fundamentes de los actos que se realicen sin perjuicio de la reserva o secreto establecido en la ley.<\/p>\n\n\n\n<p><strong>Art\u00edculo 12. Probidad.<\/strong> Los funcionarios y las funcionarias del Ministerio P\u00fablico est\u00e1n en el deber de actuar con honradez, rectitud e integridad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 13. Responsabilidad.<\/strong> Los funcionarios y las funcionarias del Ministerio P\u00fablico est\u00e1n sujetos y sujetas a responsabilidad penal, civil, administrativa o disciplinaria, con motivo del ejercicio de sus funciones.<\/p>\n\n\n\n<p><strong>Art\u00edculo 14. Formalidades esenciales y celeridad.<\/strong> El Ministerio P\u00fablico realizar\u00e1 sus atribuciones sin m\u00e1s formalidades que las establecidas en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes, garantizando la prevalencia de la justicia mediante m\u00e9todos que signifiquen simplificaci\u00f3n, eficacia y celeridad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 15. Gratuidad.<\/strong> Todas las actuaciones del Ministerio P\u00fablico ser\u00e1n gratuitas y no estar\u00e1n sujetas a obligaciones tributarias de ninguna naturaleza. Los actos que realice el Ministerio P\u00fablico se extender\u00e1n en papel com\u00fan y sin estampillas, y estar\u00e1n exentos del pago de cualquier otra clase de impuesto, tasa o contribuci\u00f3n. Los jueces o las juezas, registradores o registradoras, notarios o notarias y dem\u00e1s autoridades y funcionarios o funcionarias de la Rep\u00fablica, prestar\u00e1n gratuitamente sus servicios al Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>T\u00edtulo II<br>De las Competencias del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 16. Competencias del Ministerio P\u00fablico.<\/strong> Son competencias del Ministerio P\u00fablico:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Velar por el efectivo cumplimiento de la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, los tratados, acuerdos y convenios internacionales, v\u00e1lidamente suscritos y ratificados por la Rep\u00fablica, as\u00ed como las dem\u00e1s leyes.<\/p><p>2.- Garantizar el debido proceso, la celeridad y buena marcha de la administraci\u00f3n de justicia, el respeto de los derechos y garant\u00edas constitucionales, as\u00ed como de los tratados, convenios y acuerdos internacionales vigentes en la Rep\u00fablica, actuando de oficio o a instancia de parte.<\/p><p>3.- Ordenar, dirigir y supervisar todo lo relacionado con la investigaci\u00f3n y acci\u00f3n penal; practicar por si mismo o por el Cuerpo de Investigaciones Cient\u00edficas. Penales y Criminal\u00edsticas, o por los \u00f3rganos con competencia especial y de apoyo en materia de investigaciones penales, las actividades indagatorias para demostrar la perpetraci\u00f3n de los actos punibles; hacer constar su comisi\u00f3n con todas las circunstancias que puedan influir en la calificaci\u00f3n y establecer la responsabilidad de los autores o las autoras y dem\u00e1s participes, as\u00ed como el aseguramiento de los objetos activos y pasivos relacionados con su perpetraci\u00f3n.<\/p><p>4.- Requerir de organismos p\u00fablicos o privados altamente calificados la practica de peritajes o experticias pertinentes para el esclarecimiento de los hechos objeto de investigaci\u00f3n, sin perjuicio de la actividad que desempe\u00f1e el Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas o los \u00f3rganos con competencia especial y de apoyo en materia de investigaciones penales.<\/p><p>5.- Autorizar, en aquellos casos previstos por las leyes, las actuaciones de investigaci\u00f3n penal a ser ejercidas por el Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas, as\u00ed como de los \u00f3rganos con competencia especial y de apoyo en materia de investigaciones penales, los cuales estar\u00e1n obligados a informar al Ministerio P\u00fablico sus resultas en los plazos requeridos o, en su defecto, en los plazos fijados legalmente.<\/p><p>6.- Ejercer, en nombre del Estado, la acci\u00f3n penal en los casos en que para intentarla o proseguirla no sea necesario instancia de parte, salvo las excepciones establecidas en el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes.<\/p><p>7.- Librar y ejecutar exhortes o cartas rogatorias y solicitudes de asistencia mutua en materia penal, y ejercer las dem\u00e1s funciones inherentes en su condici\u00f3n de autoridad central en la materia.<\/p><p>8.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad civil, penal y administrativa en que hubieren incurrido los funcionarios o funcionarias del sector p\u00fablico, con motivo del ejercicio de sus atribuciones, as\u00ed como la penal y civil de los o las particulares.<\/p><p>9.- Fiscalizar la ejecuci\u00f3n de las decisiones judiciales en los procesos en los cuales el Ministerio P\u00fablico haya intervenido o cuando su intervenci\u00f3n hubiese sido requerida.<\/p><p>10.- Ejercer los recursos y acciones contra los actos dictados por el Poder P\u00fablico, viciados de inconstitucionalidad o ilegalidad, sin menoscabo de las atribuciones conferidas a la Defensor\u00eda del Pueblo y a la Procuradur\u00eda General de la Rep\u00fablica.<\/p><p>11.- Intervenir en defensa de la constitucionalidad y legalidad en los casos de nulidad de actos p\u00fablicos, que sean interpuestos por ante los diferentes \u00f3rganos de la jurisdicci\u00f3n contencioso-administrativa.<\/p><p>12.- Investigar y ejercer ante los tribunales competentes, las acciones a que hubiere lugar con ocasi\u00f3n de la violaci\u00f3n de las garant\u00edas constitucionales y derechos humanos, por parte de funcionarios p\u00fablicos o funcionarias p\u00fablicas o particulares.<\/p><p>13.- Velar por el correcto cumplimiento de las leyes y la garant\u00eda de los derechos humanos en las c\u00e1rceles y dem\u00e1s establecimientos de reclusi\u00f3n.<\/p><p>14.- Velar para que en los retenes policiales, en los establecimientos penitenciarios, en los lugares de reclusi\u00f3n para efectivos militares, en las colonias agr\u00edcolas penitenciarias, en los internados judiciales, las comunidades penitenciarias, entidades de atenci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes, y dem\u00e1s establecimientos de reclusi\u00f3n y de detenci\u00f3n, sean respetados los derechos humanos y constitucionales de los internos o internas, de los detenidos preventivamente y de los ni\u00f1os, ni\u00f1as y adolescentes; tomar en todo momento las medidas legales adecuadas para restituir y mantener la vigencia de los derechos humanos cuando hayan sido menoscabados o violados.<\/p><p>En el ejercicio de esta competencia los o las fiscales del Ministerio P\u00fablico tendr\u00e1n acceso a todos los establecimientos mencionados. Los funcionarios o las funcionarias que impidan el ejercicio de esta competencia ser\u00e1n responsables penal, civil o disciplinariamente, seg\u00fan lo dispuesto en la ley para cada caso. Asimismo, aquellos particulares que entraben de cualquier manera el ejercicio de esta competencia ser\u00e1n responsables penal y civilmente, de conformidad con las leyes seg\u00fan sea el caso.<\/p><p>15.- Solicitar, en el cumplimiento de sus funciones, la colaboraci\u00f3n de cualquier ente u organismo p\u00fablico, funcionario o funcionaria del sector p\u00fablico, quienes estar\u00e1n obligados a prestar la ayuda solicitada sin demora y a suministrar los documentos e informaciones que les sean requeridos.<\/p><p>16.- Presentar observaciones y recomendaciones a proyectos de ley y sugerir las reformas legislativas a que hubiere lugar.<\/p><p>17.- Presentar observaciones y recomendaciones en la planificaci\u00f3n de la pol\u00edtica criminal que realice el Poder Ejecutivo.<\/p><p>l8.- Las dem\u00e1s que le se\u00f1alen la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>T\u00edtulo III<br>De la Organizaci\u00f3n del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Cap\u00edtulo I<br>Del Despacho del Fiscal o la Fiscal General de la Rep\u00fablica<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 17. Sede.<\/strong> El Despacho del Fiscal o la Fiscal General de la Rep\u00fablica tendr\u00e1 su sede en la capital de la Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 18. R\u00e9gimen de personal.<\/strong> El Ministerio P\u00fablico estar\u00e1 integrado por el Fiscal o la Fiscal General de la Rep\u00fablica, o por el o la que haga sus veces, los o las fiscales y los dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal General de la Rep\u00fablica determinar\u00e1 en el Estatuto de Personal del Ministerio P\u00fablico los cargos cuyos titulares ser\u00e1n de libre nombramiento y remoci\u00f3n, en atenci\u00f3n al nivel o naturaleza de sus funciones.<\/p>\n\n\n\n<p><strong>Art\u00edculo 19. Estructura organizativa.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica determinar\u00e1 en el Estatuto Org\u00e1nico del Ministerio P\u00fablico la organizaci\u00f3n de su Despacho.<\/p>\n\n\n\n<p><strong>Cap\u00edtulo II<br>Del Fiscal o la Fiscal General de la Rep\u00fablica<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 20. Designaci\u00f3n.<\/strong> Dentro de los ciento veinte d\u00edas previos al vencimiento del periodo de siete a\u00f1os establecido para el ejercicio del cargo de Fiscal o la Fiscal General de la Rep\u00fablica, el Consejo Moral Republicano convocar\u00e1 un Comit\u00e9 de Evaluaci\u00f3n de Postulaciones del Poder Ciudadano para la designaci\u00f3n del titular del Ministerio P\u00fablico, la cual se efectuar\u00e1 conforme a lo previsto en la <a href=\"crbv.htm\"><\/a><a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y la Ley Org\u00e1nica del Poder Ciudadano.<\/p>\n\n\n\n<p><strong>Art\u00edculo 21. Juramentaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica ser\u00e1 juramentado o juramentada por la Asamblea Nacional dentro de los diez d\u00edas siguientes a su designaci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 22. Remoci\u00f3n.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica podr\u00e1 ser removido o removida por la Asamblea Nacional, con el voto favorable de la mayor\u00eda, absoluta de sus integrantes, previo pronunciamiento del Tribunal Supremo de Justicia en Sala Plena, conforme a lo dispuesto en la Ley Org\u00e1nica del Poder Ciudadano.<\/p>\n\n\n\n<p><strong>Art\u00edculo 23. Faltas graves.<\/strong> Ser\u00e1n consideradas como faltas graves del Fiscal o la Fiscal General de la Rep\u00fablica, las siguientes:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Atentar, amenazar o lesionar la \u00e9tica p\u00fablica y la moral administrativa.<\/p><p>2.- Actuar con grave e inexcusable ignorancia de la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, de la Ley y del derecho.<\/p><p>3.- Violar, amenazar o menoscabar los principios fundamentales establecidos en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>.<\/p><p>4.- Realizar activismo pol\u00edtico-partidista, gremial, sindical o de \u00edndole semejante, o efectuar actividades privadas lucrativas incompatibles con su funci\u00f3n por s\u00ed o por interpuesta persona, o ejercer cualquier otra funci\u00f3n p\u00fablica, a excepci\u00f3n de actividades acad\u00e9micas o docentes.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 24. Faltas temporales o absolutas.<\/strong> Las faltas temporales del Fiscal o la Fiscal General de la Rep\u00fablica ser\u00e1n cubiertas por el V\u00edcefiscal o 1a Vicefiscal General de la Rep\u00fablica por un m\u00e1ximo de noventa d\u00edas prorrogables, con el voto favorable de la mayor\u00eda absoluta de los integrantes de la Asamblea Nacional.<\/p>\n\n\n\n<p>Las faltas absolutas ser\u00e1n cubiertas por el Vicefiscal o la Vicefiscal hasta tanto la Asamblea Nacional, designe un nuevo Fiscal, de acuerdo con el procedimiento establecido en las leyes.<\/p>\n\n\n\n<p><strong>Art\u00edculo 25. Deberes y atribuciones.<\/strong> Son deberes y atribuciones del Fiscal o la Fiscal General de la Rep\u00fablica:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Dirigir el Ministerio P\u00fablico en los t\u00e9rminos establecidos en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, en la presente Ley, en sus reglamentos internos y en las dem\u00e1s leyes.<\/p><p>2.- Ejercer la acci\u00f3n penal p\u00fablica en todos aquellos casos se\u00f1alados en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y las leyes.<\/p><p>3.- Designar al Vicefiscal o a la Vicefiscal General de la Rep\u00fablica, previa autorizaci\u00f3n de la mayor\u00eda absoluta de los integrantes de la Asamblea Nacional; a los directores o a las directoras del Despacho, a los o a las fiscales, sus auxiliares y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico, seg\u00fan el procedimiento establecido en esta Ley y en el Estatuto de Personal del Ministerio P\u00fablico. De igual manera determinar\u00e1 los cargos cuyos titulares ser\u00e1n de libre nombramiento y remoci\u00f3n, en atenci\u00f3n al nivel o naturaleza de sus funciones.<\/p><p>4.- Organizar y distribuir las competencias del Ministerio P\u00fablico entre sus fiscales.<\/p><p>5.- Ejercer personalmente ante el Tribunal Supremo de Justicia la acci\u00f3n penal en los juicios a que se refiere el art\u00edculo 266, numerales 2 y 3 de la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>. Cuando el acusado o acusada sea el propio o la propia Fiscal General de la Rep\u00fablica, la representaci\u00f3n del Ministerio P\u00fablico ser\u00e1 ejercida por el Vicefiscal o la Vicefiscal General de la Rep\u00fablica o, en su defecto, a quien designe la Asamblea Nacional por la mayor\u00eda absoluta de sus integrantes.<\/p><p>6.- Resolver, de acuerdo al resultado de las averiguaciones realizadas por la Contralor\u00eda General de la Rep\u00fablica, si hay m\u00e9rito o no para intentar las acciones civiles, penales o administrativas contra funcionarios o funcionarias del sector p\u00fablico, con motivo del ejercido de sus funciones, de conformidad con la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p><p>7.- Ejercer personalmente o a trav\u00e9s de los o las fiscales designados o designadas para actuar ante el Tribunal Supremo de Justicia, las acciones de nulidad contra los actos del Poder P\u00fablico que sean inconstitucionales o ilegales, sin perjuicio de las atribuciones que corresponden al Defensor o Defensora del Pueblo y al Procurador o Procuradora General de la Rep\u00fablica.<\/p><p>8.- Dictar el Estatuto Org\u00e1nico del Ministerio P\u00fablico y las dem\u00e1s normas de car\u00e1cter interno que considere necesarias para el ejercicio de las atribuciones que le confieren la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p><p>9.- Presentar anualmente a la Asamblea Nacional, en sesi\u00f3n plenaria, dentro de los primeros treinta d\u00edas siguientes al inicio de las sesiones ordinarias, un informe de su actuaci\u00f3n durante el a\u00f1o anterior.<\/p><p>10.- Participar en la reestructuraci\u00f3n de la pol\u00edtica criminal del Estado y emitir opini\u00f3n razonada, cuando lo juzgue conveniente o le sea solicitada por la Asamblea Nacional, sobre los proyectos de ley que tengan relaci\u00f3n con el Ministerio P\u00fablico y la administraci\u00f3n de justicia, as\u00ed como de aquellos que a su juicio lo requieran, y sugerir e indicar las reformas legislativas tendentes a mejorarlos.<\/p><p>11.- Elaborar cada a\u00f1o el Proyecto de Presupuesto de Gastos del Ministerio P\u00fablico y enviarlo al ministerio responsable de las finanzas p\u00fablicas; \u00e9ste, a su vez y de manera definitiva, lo incorporar\u00e1 sin modificaci\u00f3n al presupuesto general del Estado.<\/p><p>12.- Intervenir personalmente, cuando lo juzgue conveniente, en los procesos judiciales de la jurisdicci\u00f3n ordinaria o especial en materias de su competencia, en cualquier lugar del territorio nacional. A tales efectos, tambi\u00e9n podr\u00e1 designar a uno de sus funcionarios o funcionarias del Ministerio P\u00fablico.<\/p><p>13.- Fijar las pautas generales y espec\u00edficas en cuanto a la direcci\u00f3n funcional del Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas, as\u00ed como de los \u00f3rganos con competencia especial y de apoyo en la investigaci\u00f3n penal. En atenci\u00f3n a las pautas dictadas y aspectos de la competencia del Ministerio P\u00fablico, se har\u00e1 la debida supervisi\u00f3n y consecuencialmente se instrumentar\u00e1n las acciones legales consiguientes s\u00ed en el proceso de supervisi\u00f3n o mediante cualquier otra actividad realizada por el Ministerio P\u00fablico, se detectaren fallas, faltas o cualquier otro tipo de acto que afecten su funcionalidad.<\/p><p>14.- Solicitar de las autoridades competentes la imposici\u00f3n de las sanciones disciplinarias, de acuerdo con la ley que los rija, cuando los funcionarios o funcionarias de investigaciones penales, se\u00f1alados en el numeral anterior, infrinjan disposiciones legales o reglamentarias, omitan o retarden la ejecuci\u00f3n de un acto propio de sus funciones o lo cumplan negligentemente. No obstante, el Fiscal o la Fiscal General de la Rep\u00fablica podr\u00e1 aplicar directamente cualesquiera de las sanciones disciplinarias legalmente dispuestas, previa audiencia del funcionario o funcionaria, y luego de cumplido el respectivo procedimiento, cuando las autoridades correspondientes, en el t\u00e9rmino de treinta d\u00edas continuos a partir de su notificaci\u00f3n, no cumplan con su potestad disciplinaria. El \u00f3rgano de adscripci\u00f3n del funcionario o funcionaria ser\u00e1 responsable del efectivo cumplimiento de la sanci\u00f3n impuesta.<\/p><p>15.- Opinar e intervenir, directamente o a trav\u00e9s de los o las fiscales ante el Tribunal Supremo de Justicia, en los procedimientos relativos a la ejecuci\u00f3n de actos de autoridades extranjeras, en los de extradici\u00f3n y cuando alguna ley especial disponga su intervenci\u00f3n, A tal efecto, el Tribunal Supremo de Justicia ordenara la notificaci\u00f3n correspondiente.<\/p><p>16.- Ejercer la potestad disciplinaria sobre los o las fiscales y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico.<\/p><p>17.- Conceder licencias y permisos a los funcionarios o funcionarias de su Despacho, de conformidad con lo previsto en esta Ley y en el Estatuto de Personal del Ministerio P\u00fablico.<\/p><p>18.- Solicitar de los jueces o juezas en materia civil, la notificaci\u00f3n inmediata a el o a la Fiscal Superior correspondiente, de todas las causas que se inicien en sus juzgados, en las que est\u00e9n interesados el orden p\u00fablico y las buenas costumbres, cuando no exista en una determinada circunscripci\u00f3n judicial un representante especial del Ministerio P\u00fablico para asuntos de familia.<\/p><p>19.- Convocar convenciones, congresos, foros y otros eventos de fiscales y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico.<\/p><p>20.- Delegar en funcionarios o funcionarias de su Despacho determinadas atribuciones de car\u00e1cter administrativo, as\u00ed como la firma de los asuntos rutinarios o de mera tramitaci\u00f3n, a los fines del mejor funcionamiento del organismo.<\/p><p>21.- Impartir instrucciones para cumplir con eficacia los deberes a cargo del Ministerio P\u00fablico, y procurar la unidad de acci\u00f3n de los funcionarios o las funcionarias al servicio del organismo.<\/p><p>22.- Impartir instrucciones a cualquier Fiscal del Ministerio P\u00fablico para que coopere con otro fiscal u otra fiscal de la misma o de distinta circunscripci\u00f3n o circuito judicial, o lo reemplace, seg\u00fan sea el caso.<\/p><p>23.- Solicitar informaci\u00f3n a cualquier fiscal y dem\u00e1s funcionarios o funcionarias del Ministerio Publico, cuando lo estime pertinente.<\/p><p>24.- Contratar profesionales, t\u00e9cnicos o expertos en determinadas materias, quienes estar\u00e1n excluidos del \u00e1mbito de aplicaci\u00f3n de la presente Ley.<\/p><p>25.- Las dem\u00e1s que les sean atribuidas por la <a href=\"crbv.htm\">Constituci\u00f3n de Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Cap\u00edtulo III<br>Del Vicefiscal o la Vicefiscal General de la Rep\u00fablica y de los Fiscales o las Fiscales Superiores del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 26. Vicefiscal.<\/strong> Para ser Vicefiscal se requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Tener nacionalidad venezolana por nacimiento y no poseer ninguna otra.<\/p><p>2.- Ser mayor de treinta a\u00f1os de edad.<\/p><p>3.- Ser abogado o abogada y tener titulo universitario de postgrado en materia jur\u00eddica.<\/p><p>4.- Ser de notoria buena conducta y de reconocida solvencia moral.<\/p><p>5. Estar en pleno goce de sus derechos civiles y pol\u00edticos.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 27. De los Fiscales o las Fiscales Superiores.<\/strong> En cada una de las circunscripciones judiciales, el Fiscal o la Fiscal General de la Rep\u00fablica designar\u00e1 Fiscales Superiores que representar\u00e1n al Ministerio P\u00fablico y ejercer\u00e1n las atribuciones que les confiere esta Ley. El cargo de Fiscal Superior o de la Fiscal Superior es de libre nombramiento y remoci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 28. Requisitos.<\/strong> Para ser Fiscal Superior del Ministerio P\u00fablico se requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ser mayor de treinta a\u00f1os de edad.<\/p><p>2.- Ser abogado o abogada, preferiblemente con estudios de cuarto nivel en Ciencias Penales o Procesal Penal, expedido por una universidad nacional o extranjera, debidamente revalidado por una universidad p\u00fablica nacional.<\/p><p>3.- Ser profesor universitario o profesora universitaria en materia jur\u00eddica, de reconocida competencia o haber ejercido el cargo de Fiscal del Ministerio P\u00fablico, o Juez o Jueza o Defensor P\u00fablico o Defensora P\u00fablica Penal durante un periodo no menor de cinco a\u00f1os o haber ejercido la profesi\u00f3n de abogado o abogada durante un m\u00ednimo de ocho a\u00f1os.<\/p><p>4.- Cumplir con los requisitos establecidos en el art\u00edculo 30 de esta Ley, con excepci\u00f3n de lo previsto en los numerales 2, 9, 10 y 11.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 19. Atribuciones y Deberes de los Fiscales o las Fiscales Superiores.<\/strong> Son atribuciones y deberes de los Fiscales o las Fiscales superiores:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer la representaci\u00f3n del Ministerio P\u00fablico en la circunscripci\u00f3n judicial correspondiente.<\/p><p>2.- Dirigir la Unidad de Atenci\u00f3n a la Victima y la Oficina de Atenci\u00f3n al Ciudadano.<\/p><p>3.- Coordinar y supervisar, junto con el director de adscripci\u00f3n correspondiente, la actuaci\u00f3n de los o las fiscales del Ministerio P\u00fablico en la respectiva circunscripci\u00f3n judicial.<\/p><p>4.- Tomar las decisiones en relaci\u00f3n a los procesos que le son atribuidas por el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes.<\/p><p>5.- Elevar consultas al Fiscal General de la Rep\u00fablica cuando lo juzguen necesario, para el mejor desempe\u00f1o de sus atribuciones.<\/p><p>6.- Recibir y comunicar de inmediato al Fiscal o a la Fiscal General de la Rep\u00fablica las recusaciones e inhibiciones relativas a fiscales del Ministerio P\u00fablico de su circunscripci\u00f3n judicial, conforme a las normas previstas en esta Ley.<\/p><p>7.- Tramitar ante la Direcci\u00f3n competente las denuncias relacionadas con las actuaciones de los o las fiscales del Ministerio P\u00fablico que se desempe\u00f1en en la respectiva circunscripci\u00f3n judicial.<\/p><p>8.- Supervisar y controlar el funcionamiento administrativo de las unidades respectivas.<\/p><p>9.- Disponer las medidas que faciliten y aseguren el acceso expedito de las personas a su Despacho y al de los o las dem\u00e1s fiscales, as\u00ed como su debida atenci\u00f3n.<\/p><p>10.- Autorizar y tramitar inmediatamente las solicitudes de consultores t\u00e9cnicos que le formulen los o las fiscales.<\/p><p>11.- Solicitar al Fiscal o a la Fiscal General de la Rep\u00fablica o a la Direcci\u00f3n que corresponda, la creaci\u00f3n de fiscal\u00edas y de cargos para fiscales auxiliares y dem\u00e1s funcionarios o funcionarias dentro de su respectiva circunscripci\u00f3n judicial, cuando las necesidades de servicio as\u00ed lo requieran.<\/p><p>12.- Rendir cuenta al Fiscal o a la Fiscal General de la Rep\u00fablica, por intermedio de su Direcci\u00f3n de adscripci\u00f3n, en el mes de enero de cada a\u00f1o, sobre las actividades desarrolladas por la Fiscal\u00eda a su cargo en la respectiva circunscripci\u00f3n. En la Cuenta se reflejar\u00e1n las estad\u00edsticas de las actividades realizadas y de los resultados obtenidos, el uso de los recursos otorgados y las dificultades que se presentaron.<\/p><p>l3.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Cap\u00edtulo IV<br>De los Fiscales o las Fiscales del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 30. Requisitos.<\/strong> Para ser Fiscal del Ministerio P\u00fablico se requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Tener nacionalidad venezolana.<\/p><p>2.- Ser mayor de veinticinco a\u00f1os de edad.<\/p><p>3.- Ser abogado o abogada.<\/p><p>4.- Ser de notoria buena conducta y de reconocida solvencia moral.<\/p><p>5.- Estar en pleno goce de sus derechos civiles y pol\u00edticos.<\/p><p>6.- No estar inhabilitado o inhabilitada para el ejercicio de la funci\u00f3n p\u00fablica.<\/p><p>7.- No haber sido objeto de sanci\u00f3n penal, por decisi\u00f3n definitivamente firme, por la comisi\u00f3n de un delito.<\/p><p>8.- No haber sido objeto de sanci\u00f3n disciplinaria de suspensi\u00f3n del ejercicio de las funciones por decisi\u00f3n definitivamente firme, durante los cinco a\u00f1os previos a la celebraci\u00f3n del concurso, ni de sanci\u00f3n disciplinaria de destituci\u00f3n del ejercicio de las funciones por decisi\u00f3n definitivamente firme, durante los diez a\u00f1os previos a la celebraci\u00f3n del concurso.<\/p><p>9.- Preferiblemente haber cursado estudios de especializaci\u00f3n en el \u00e1rea objeto del concurso, en una universidad nacional o extranjera, debidamente acreditada. En caso de no existir cursos de especializaci\u00f3n en la referida \u00e1rea, en una que resulte af\u00edn a aquella a ser ejercida en el cargo objeto del concurso.<\/p><p>10.- Haber sido Fiscal del Ministerio P\u00fablico o Juez o Jueza o Defensor P\u00fablico o Defensora P\u00fablica Penal; o haber sido profesor universitario o profesora universitaria por un m\u00ednimo de tres a\u00f1os; o haber ejercido la abogac\u00eda durante un m\u00ednimo de cinco a\u00f1os.<\/p><p>11.- Haber aprobado los concursos de credenciales y de oposici\u00f3n en los t\u00e9rminos establecidos en la presente Ley.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 31. Deberes y atribuciones.<\/strong> Son deberes y atribuciones comunes de los fiscales o las fiscales del Ministerio P\u00fablico:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Garantizar en los procesos judiciales y administrativos, en todas sus fases, el respeto de los derechos y garant\u00edas constitucionales, actuando de oficio o a instancia de parte. Lo anterior no menoscaba el ejercicio de los derechos y acciones que corresponden a los particulares.<\/p><p>2.- Garantizar, en cuanto le compete, el juicio previo y el debido proceso, la recta aplicaci\u00f3n de la ley, la celeridad y buena marcha de la administraci\u00f3n de justicia.<\/p><p>3.- Proteger el inter\u00e9s p\u00fablico, actuar con objetividad, teniendo en cuenta la situaci\u00f3n del imputado o imputada y de la victima, y prestar atenci\u00f3n a todas las circunstancias pertinentes del caso.<\/p><p>4.- Promover la acci\u00f3n de la justicia en todo cuanto concierne al inter\u00e9s p\u00fablico y en los casos establecidos por las leyes.<\/p><p>5.- Interponer, desistir o contestar los recursos contra las decisiones judiciales dictadas en cualquier estado y grado del proceso.<\/p><p>6.- Velar por el exacto cumplimiento de los lapsos, plazos y t\u00e9rminos legales y, en caso de inobservancia por parte de los jueces o juezas, hacer la correspondiente denuncia ante los organismos competentes.<\/p><p>7.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad civil, militar, penal, administrativa en que incurran los funcionarios o funcionarias del sector p\u00fablico con motivo del ejercicio de sus funciones, as\u00ed como la responsabilidad penal y civil de los particulares.<\/p><p>8.- Ejercer las acciones que se deriven de la violaci\u00f3n de la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> o de los tratados internacionales vigentes en la Rep\u00fablica.<\/p><p>9.- Elevar consultas debidamente motivadas al o a la Fiscal General de la Rep\u00fablica cuando lo juzguen necesario para el mejor desempe\u00f1o de sus funciones.<\/p><p>10.- Ordenar al Fiscal Auxiliar respectivo la pr\u00e1ctica de las actuaciones que sean pertinentes dentro del marco de sus atribuciones legales.<\/p><p>11.- Ordenar, dirigir y supervisar las actividades del Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas, as\u00ed como de los \u00f3rganos con competencia especial y de apoyo en materia de investigaciones penales dentro del curso de la investigaci\u00f3n.<\/p><p>12.- Velar por la disciplina y el eficaz desempe\u00f1o del personal a su cargo y conceder licencias y permisos conforme a lo previsto en el Estatuto de Personal del Ministerio P\u00fablico.<\/p><p>13.- Las dem\u00e1s que les sean atribuidas por la <a href=\"crbv.htm\">Constituci\u00f3n<\/a> y las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Primera<br>De los Fiscales o las Fiscales del Ministerio P\u00fablico ante el Tribunal Supremo de Justicia<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 32. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico ante el Tribunal Supremo de Justicia, aquellos o aquellas a quienes les corresponde ejercer la representaci\u00f3n de la instituci\u00f3n ante las Salas correspondientes de ese m\u00e1ximo tribunal.<\/p>\n\n\n\n<p><strong>Art\u00edculo 33. Requisitos.<\/strong> Para ser Fiscal del Ministerio P\u00fablico ante el Tribunal Supremo de Justiciase requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ser mayor de treinta a\u00f1os de edad.<\/p><p>2.- Haber sido profesor universitario o profesora universitaria de reconocida competencia en ciencia jur\u00eddica durante un m\u00ednimo de siete a\u00f1os; o haber ejercido el cargo de Fiscal del Ministerio Publico, o Juez o Jueza o Defensor P\u00fablico o Defensora P\u00fablica Penal durante un m\u00ednimo de siete a\u00f1os; o haber ejercido la abogac\u00eda durante un m\u00ednimo de diez a\u00f1os.<\/p><p>3.- Cumplir con los requisitos establecidos en el art\u00edculo 30 de esta Ley, con excepci\u00f3n de lo previsto en su numeral 2 y 10.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 34. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los o las Fiscales del Ministerio P\u00fablico ante el Tribunal Supremo de Justicia en Sala Plena y en Salas Constitucional y Pol\u00edtico administrativa, seg\u00fan corresponda:<\/p>\n\n\n\n<p>1.- Intentar previa delegaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>a.- Recursos o acciones de nulidad por razones de inconstitucionalidad o ilegalidad contra actos, hechos u omisiones emanados de autoridades del Poder P\u00fablico Nacional, Estadal o Municipal.<\/p><p>b.- Recursos de colisi\u00f3n.<\/p><p>c.- Recursos de interpretaci\u00f3n.<\/p><p>d.- Recursos de apelaci\u00f3n contra las decisiones dictadas por los tribunales de la jurisdicci\u00f3n contencioso-administrativa, que act\u00faen en primera instancia.<\/p><p>e.- Acciones o recursos contra la negativa o abstenci\u00f3n de las autoridades nacionales, estadales o municipales, a cumplir determinados actos, a que est\u00e9n obligadas legalmente, cuando sea procedente, de conformidad con las leyes respectivas.<\/p><p>f.- Acciones de amparo constitucional.<\/p><p>g.- Cualquier otro recurso o acci\u00f3n donde sea procedente la intervenci\u00f3n del Ministerio P\u00fablico, de conformidad con las leyes.<\/p><\/blockquote>\n\n\n\n<p>2.- Intervenir, previa delegaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica, en los juicios de expropiaci\u00f3n intentados por la Rep\u00fablica, los estados o los municipios.<\/p>\n\n\n\n<p>3.- Ejercer, previa designaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica, la representaci\u00f3n judicial del Ministerio P\u00fablico cuando sus actos sean impugnados.<\/p>\n\n\n\n<p>4.- Elevar consultas al Fiscal o la Fiscal General de la Rep\u00fablica cuando lo juzguen necesario para el mejor desempe\u00f1o de sus funciones.<\/p>\n\n\n\n<p>5.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p>\n\n\n\n<p><strong>Art\u00edculo 35. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales designados o las Fiscales designadas ante el Tribunal Supremo de Justicia, en Sala Plena, Sala Constitucional y Sala de Casaci\u00f3n:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer la atribuci\u00f3n prevista en el numeral 6 del art\u00edculo 16 de esta Ley.<\/p><p>2.- Intervenir como representantes del Ministerio P\u00fablico, aun cuando la acci\u00f3n hubiere sido intentada o proseguida por el Fiscal o la Fiscal General de la Rep\u00fablica, en las causas penales de acci\u00f3n p\u00fablica y en las de responsabilidad que se intenten contra los altos funcionarios se\u00f1alados en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>.<\/p><p>3.- Intervenir y opinar, cuando no lo hiciere personalmente el Fiscal o la Fiscal General de la Rep\u00fablica, en los procedimientos relativos a la ejecuci\u00f3n de actos de autoridad extranjera, procedimiento de extradici\u00f3n y cuando alguna ley especial disponga su intervenci\u00f3n, sin perjuicio de que el Tribunal Supremo de Justicia efect\u00fae las notificaciones correspondientes.<\/p><p>4.- Las dem\u00e1s que les sean atribuidas por la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Segunda<br>De los o las Fiscales del Ministerio P\u00fablica de Proceso<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 36. Fiscal del Ministerio P\u00fablico de Proceso.<\/strong> Son Fiscales del Ministerio P\u00fablico de Proceso, aquellos o aquellas que en esta Ley, el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes tengan atribuida participaci\u00f3n en procesos judiciales de cualquier naturaleza. En cada Circuito Judicial Penal existir\u00e1n los Fiscales de Proceso que sean indispensables para el cumplimiento de las funciones del Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>Art\u00edculo 37. Atribuciones y deberes.<\/strong> Son atribuciones y deberes de los Fiscales o las Fiscales del Ministerio P\u00fablico de Proceso:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer la atribuci\u00f3n prevista consagrada en el numeral 6 del art\u00edculo 16 de esta Ley.<\/p><p>2.- Solicitar autorizaci\u00f3n al tribunal de control para prescindir o suspender el ejercicio de la acci\u00f3n penal.<\/p><p>3.- Ejercer la acci\u00f3n civil derivada del delito cuando as\u00ed lo dispongan el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes.<\/p><p>4.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad civil, penal y administrativa en que hubieren incurrido los funcionarios o funcionarias del sector p\u00fablico, con motivo del ejercicio de sus funciones, as\u00ed como de los particulares.<\/p><p>5.- Atender las solicitudes de protecci\u00f3n a las victimas, testigos y expertos, y procurar que sean informados acerca de sus derechos, con arreglo al <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes.<\/p><p>6.- Ordenar el inicio de la investigaci\u00f3n cuando tengan conocimiento de la presunta comisi\u00f3n de alg\u00fan hecho punible.<\/p><p>7.- Garantizar que a todas las partes y personas que intervengan en el proceso les sean respetados sus derechos constitucionales y legales.<\/p><p>8.- Ordenar o practicar la citaci\u00f3n del imputado o imputada o de cualquiera que se requiera, a los fines de la investigaci\u00f3n. En caso de negarse a comparecer, podr\u00e1n solicitar al tribunal de control el auxilio de la fuerza p\u00fablica para hacer efectiva su inmediata comparecencia.<\/p><p>9.- Ordenar y dirigir las investigaciones penales y las actuaciones que realicen los \u00f3rganos de polic\u00eda de investigaciones penales, supervisar la legalidad de las actividades correspondientes y disponer todo lo referente a la adquisici\u00f3n y conservaci\u00f3n de los elementos de convicci\u00f3n.<\/p><p>10.- Promover y realizar, durante la fase preparatoria de la investigaci\u00f3n penal, todo cuanto estimen conveniente al mejor esclarecimiento de los hechos. En el ejercicio de esta atribuci\u00f3n, podr\u00e1n requerir de organismos p\u00fablicos o privados, altamente calificados, la pr\u00e1ctica de peritajes o experticias pertinentes para el esclarecimiento de los hechos objeto de investigaci\u00f3n, sin perjuicio de la actividad que desempe\u00f1en los \u00f3rganos del Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas, as\u00ed como de los \u00f3rganos con competencia especial y de apoyo en materia de investigaciones penales dentro del curso de la investigaci\u00f3n.<\/p><p>11.- Solicitar, previa autorizaci\u00f3n del Fiscal o de la Fiscal Superior correspondiente, los expertos y consultores t\u00e9cnicos que consideren necesarios para el mejor esclarecimiento de los hechos que se investigan. Proponer la recusaci\u00f3n contra los funcionarios o funcionarias judiciales, as\u00ed como la de los escabinos o las escabinas de conformidad con lo previsto en el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a>.<\/p><p>12.- Investigar las detenciones inconstitucionales o ilegales y promover las actuaciones para determinar las responsabilidades a que haya lugar.<\/p><p>13.- Solicitar y ejecutar exhortes o cartas rogatorias, as\u00ed como instrumentar, solicitar y ejecutar la cooperaci\u00f3n internacional con base en los tratados internacionales vigentes para la Rep\u00fablica Bolivariana de Venezuela.<\/p><p>14.- Solicitar al superior jer\u00e1rquico de los funcionarios o las funcionarias de investigaciones penales la apertura del correspondiente procedimiento disciplinario, en caso de violaci\u00f3n de una disposici\u00f3n legal o reglamentaria u omitan o incumplan, retarden indebidamente o cumplan negligentemente una orden o instrucci\u00f3n comprendida en el marco de sus atribuciones legales. Tanto de la solicitud como de las resultas de la misma, deber\u00e1 informar al Fiscal o a la Fiscal General de la Rep\u00fablica a objeto de que se impongan las sanciones, de acuerdo con lo se\u00f1alado en la presente Ley y los otros instrumentos legales.<\/p><p>15.- Ejercer todos los actos conclusivos, de conformidad con el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a>.<\/p><p>16.- Las dem\u00e1s que les sean atribuidas por el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Tercera<br>De los o las Fiscales del Ministerio P\u00fablico de Ejecuci\u00f3n de la Sentencia<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 38. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico de Ejecuci\u00f3n de la Sentencia, aquellos o aquellas a quienes corresponde la supervisi\u00f3n de la correcta aplicaci\u00f3n de la pena y la vigilancia del respeto a los derechos y garant\u00edas que la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, los tratados, convenios y acuerdos internacionales vigentes en la Rep\u00fablica y dem\u00e1s leyes le otorgan al penado o penada, o al sometido o a la sometida a medida de seguridad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 39. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o de las Fiscales del Ministerio P\u00fablico de ejecuci\u00f3n de la sentencia:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Solicitar al tribunal competente la revisi\u00f3n de condenas penales en los casos se\u00f1alados en el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> y dem\u00e1s leyes.<\/p><p>2.- Revisar las solicitudes de concesi\u00f3n de beneficios durante la fase de ejecuci\u00f3n de sentencias, y ejercer la representaci\u00f3n del Ministerio P\u00fablico con ocasi\u00f3n de las mismas.<\/p><p>3.- Solicitar la revocatoria de las medidas concedidas cuando el penado o penada incumpla con las obligaciones impuestas por el tribunal o cuando as\u00ed lo determine la ley.<\/p><p>4.- Ejercer los recursos contra las decisiones de los tribunales de ejecuci\u00f3n de sentencias cuando no se ajusten a la legalidad.<\/p><p>5.- Ejercer ante los tribunales competentes las acciones a que hubiere lugar con ocasi\u00f3n de la violaci\u00f3n de derechos humanos en las c\u00e1rceles y dem\u00e1s establecimientos de reclusi\u00f3n.<\/p><p>6.- Comunicar al o a la Fiscal Superior de la circunscripci\u00f3n judicial respectiva la perpetraci\u00f3n de hechos punibles o la violaci\u00f3n a los derechos humanos, en los establecimientos penitenciarios de los cuales tenga conocimiento por cualquier medio.<\/p><p>7.- Vigilar e inspeccionar para que en los retenes policiales, en los locales carcelarios, en los lugares de reclusi\u00f3n de los comandos militares, en las colonias de trabajo, en las c\u00e1rceles y penitenciarias, institutos de correcci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes, y dem\u00e1s establecimientos de reclusi\u00f3n e internamiento, sean respetados los derechos humanos y constitucionales de los reclusos o reclusas, y de los ni\u00f1os, ni\u00f1as o adolescentes, vigilar las condiciones en que se encuentren los reclusos o reclusas, internados e internadas, tomar las medidas legales adecuadas para mantener la vigencia de los derechos humanos cuando se compruebe que han sido o son menoscabados o violados.<\/p><p>En el ejercicio de esta atribuci\u00f3n constitucional, los funcionarios del Ministerio P\u00fablico tendr\u00e1n acceso a todos los establecimientos mencionados. Quienes entraben de alguna forma el ejercicio de esa atribuci\u00f3n incurrir\u00e1n en responsabilidad disciplinaria.<\/p><p>8.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Cuarta<br>De los Fiscales o las Fiscales del Ministerio P\u00fablico de los Derechos y Garant\u00edas Constitucionales<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 40. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico de los Derechos y Garant\u00edas Constitucionales, aquellos o aquellas a quienes corresponde garantizar en los procesos judiciales y procedimientos administrativos, el respeto a los derechos y garant\u00edas establecidos en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, as\u00ed como en los tratados, convenios y acuerdos internacionales vigentes en la Rep\u00fablica, e impugnar, cuando as\u00ed lo ordene el Fiscal o la Fiscal General de la Rep\u00fablica, los actos de efectos generales contrarios a la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y las leyes.<\/p>\n\n\n\n<p><strong>Art\u00edculo 41. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los o las Fiscales del Ministerio P\u00fablico de los derechos y garant\u00edas constitucionales:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer las acciones por inconstitucionalidad e ilegalidad de los actos del Poder P\u00fablico de efectos generales, cuando as\u00ed lo ordene el Fiscal o la Fiscal General de la Rep\u00fablica.<\/p><p>2.- Ejercer las acciones a que hubiere lugar para hacer efectiva la responsabilidad civil, administrativa, disciplinaria, laboral y militar de los funcionarios p\u00fablicos o funcionarias p\u00fablicas por violaciones de derechos humanos.<\/p><p>3.- Garantizar la celeridad procesal, el juicio previo y el debido proceso en sede administrativa y judicial.<\/p><p>4.- Comunicar al Fiscal o la Fiscal Superior de la circunscripci\u00f3n judicial respectiva, la perpetraci\u00f3n de hechos punibles, de los cuales tenga conocimiento por cualquier medio.<\/p><p>5.- Ejercer las acciones de amparo constitucional e intervenir en las mismas.<\/p><p>6.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Quinta<br>De los o las Fiscales del Ministerio P\u00fablico en el Sistema de Protecci\u00f3n del Ni\u00f1o, Ni\u00f1a, Adolescente y la Familia<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 42. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico en el Sistema de Protecci\u00f3n del Ni\u00f1o. Ni\u00f1a, Adolescente y la Familia, aquellos o aquellas a quienes corresponde garantizar, en los procesos judiciales y administrativos, el respeto de los derechos y garant\u00edas de los ni\u00f1os, ni\u00f1as y adolescentes, e intervenir en aquellos procesos en que est\u00e9 involucrado el orden p\u00fablico y las buenas costumbres, de conformidad con lo establecido en esta Ley, los rotados internacionales vigentes en la Rep\u00fablica y las leyes que rigen la materia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 43. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o las Fiscales del Ministerio P\u00fablico en el Sistema de Protecci\u00f3n del Ni\u00f1o, Ni\u00f1a, Adolescente y la Familia, las siguientes:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Intervenir en resguardo del orden p\u00fablico y las buenas costumbres en los juicios relativos al estado civil de las personas y en materia de emancipaci\u00f3n, adopci\u00f3n y otras de cualquier naturaleza, de conformidad con el <a href=\"cpc.htm\">C\u00f3digo de Procedimiento Civil<\/a> y otras leyes.<\/p><p>2.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad civil, laboral o administrativa de las personas naturales o jur\u00eddicas, seg\u00fan sea el caso, que por acci\u00f3n u omisi\u00f3n violen o amenacen derechos individuales, colectivos o difusos de ni\u00f1os, ni\u00f1as y adolescentes.<\/p><p>3.- Recibir de los Organismos competentes en materia del ni\u00f1o, ni\u00f1a y del adolescente las denuncias sobre infracciones de car\u00e1cter, civil, laboral o administrativa contra ni\u00f1os, ni\u00f1as y adolescentes.<\/p><p>4.- Defender el inter\u00e9s superior del ni\u00f1o, ni\u00f1a y del adolescente en los procedimientos judiciales y administrativos.<\/p><p>5.- Inspeccionar las entidades de atenci\u00f3n y las Defensor\u00edas del Ni\u00f1o. Ni\u00f1a y del Adolescente e instar a los Consejos Estadales y Municipales de Derechos para que impongan las medidas a que hubiere lugar cuando se comprueben irregularidades en la prestaci\u00f3n de los servicios correspondientes.<\/p><p>6.- Denunciar ante los Organismos competentes en materia de derechos del Ni\u00f1o, Ni\u00f1a y del Adolescente las irregularidades observadas en el funcionamiento de las entidades de atenci\u00f3n, o en las Defensorios del Ni\u00f1o, Ni\u00f1a y del Adolescente, a los fines de que se inicie el procedimiento administrativo establecido en la <a href=\"lopna.htm\">Ley Org\u00e1nica para la Protecci\u00f3n del Ni\u00f1o y del Adolescente<\/a>.<\/p><p>7.- Promover la conciliaci\u00f3n, la mediaci\u00f3n y cualesquiera otros medios alternativos para la soluci\u00f3n de conflictos, en inter\u00e9s del ni\u00f1o, ni\u00f1a y el adolescente, en los t\u00e9rminos previstos en la ley.<\/p><p>8.- Solicitar a las autoridades la informaci\u00f3n, experticias y documentos necesarios para el mejor ejercicio de sus atribuciones.<\/p><p>9.- Solicitar a instituciones privadas o particulares la informaci\u00f3n que sea necesaria para la mejor defensa de los derechos e intereses de los ni\u00f1os, ni\u00f1as y adolescentes.<\/p><p>10.- Recibir las notificaciones de los \u00f3rganos jurisdiccionales y emitir opini\u00f3n o formular las observaciones pertinentes en los procesos en que sean llamados a intervenir.<\/p><p>11.- Interponer, por ante el \u00f3rgano jurisdiccional competente, los asuntos contenciosos del trabajo de ni\u00f1os, ni\u00f1as y adolescentes.<\/p><p>12.- Interponer la acci\u00f3n de privaci\u00f3n de patria potestad. de oficio o a solicitud del hijo o hija, a partir de los doce a\u00f1os de edad, de los ascendientes, de los dem\u00e1s parientes del hijo o la hija dentro del cuarto grado en cualquier l\u00ednea, de la persona que ejerza la guarda y de los Organismos con competencia en materia del ni\u00f1o, ni\u00f1a y del adolescente.<\/p><p>13.- Intervenir en todos los procesos judiciales en los cuales se requiera su actuaci\u00f3n de conformidad con la ley.<\/p><p>14.- Intervenir en los juicios de restituci\u00f3n de patria potestad.<\/p><p>15.- Solicitar la revisi\u00f3n y modificaci\u00f3n de la guarda y, en todo caso, opinar en relaci\u00f3n a la misma.<\/p><p>16.- Solicitar la fijaci\u00f3n de la obligaci\u00f3n alimentaria y opinar sobre su cumplimiento.<\/p><p>17.- Solicitar la colocaci\u00f3n familiar o la revocatoria de la misma.<\/p><p>18.- Emitir opini\u00f3n, formular las observaciones y hacer las oposiciones que sean necesarias en las solicitudes de adopci\u00f3n en que hayan sido notificados o notificadas y, de ser procedente, solicitar la pr\u00f3rroga del periodo de prueba.<\/p><p>19.- Intentar la acci\u00f3n de nulidad de la adopci\u00f3n.<\/p><p>20.- Intervenir en las causas relativas a la rectificaci\u00f3n de los actos del estado civil y de la filiaci\u00f3n.<\/p><p>21.- Intervenir en la tacha de instrumentos.<\/p><p>22.- Ejercer los recursos ordinarios y extraordinarios a los que haya lugar.<\/p><p>23.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad penal de las personas que incurran en delitos contra ni\u00f1os, ni\u00f1as y adolescentes.<\/p><p>24.- Solicitar la apertura de los procedimientos de tutela y c\u00faratela para aquellos ni\u00f1os, ni\u00f1as y adolescentes que carezcan de representante legal.<\/p><p>25.- Las dem\u00e1s previstas en la <a href=\"lopna.htm\">Ley Org\u00e1nica para la Protecci\u00f3n del Ni\u00f1o, Ni\u00f1a y del Adolescente<\/a>, el <a href=\"cpc.htm\">C\u00f3digo de Procedimiento Civil<\/a>, el <a href=\"cc.htm\">C\u00f3digo Civil<\/a> y las que les atribuyan las dem\u00e1s leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Sexta<br>De los o las fiscales del Ministerio P\u00fablico en el Sistema Penal de Responsabilidad del Adolescente<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 44. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico en el Sistema Penal de Responsabilidad del Adolescente, aquellos o aquellas a quienes se les atribuye el ejercicio de las acciones tendentes a establecer la responsabilidad del adolescente por los hechos punibles en que incurra, de acuerdo con lo previsto en la ley especial que rige la materia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 45. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o de las Fiscales del Ministerio P\u00fablico en el Sistema Penal de Responsabilidad del Adolescente:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Realizar u ordenar, dirigir y supervisar la investigaci\u00f3n de los hechos punibles con participaci\u00f3n de adolescentes.<\/p><p>2.- Ejercer la acci\u00f3n penal, en los t\u00e9rminos y condiciones establecidos en la ley.<\/p><p>3.- Solicitar y aportar pruebas conforme a lo previsto en la ley.<\/p><p>4.- Solicitar la imposici\u00f3n, modificaci\u00f3n, sustituci\u00f3n o cesaci\u00f3n de las medidas cautelares o sanciones acordadas.<\/p><p>5.- Interponer los recursos ordinarios y extraordinarios a que haya lugar.<\/p><p>6.- Asesorar a la v\u00edctima durante la mediaci\u00f3n, la conciliaci\u00f3n y cualesquiera otros medios alternativos para la soluci\u00f3n de conflictos cuando ella lo solicite.<\/p><p>7.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n S\u00e9ptima<br>De los o las Fiscales del Ministerio P\u00fablico en Defensa Ambiental<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 46. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico en Defensa Ambiental, aquellos o aquellas a quienes corresponde el ejercicio de las acciones penales y civiles derivadas de la comisi\u00f3n de hechos punibles de car\u00e1cter ambiental, y las dem\u00e1s atribuciones que les confieren las leyes, relacionadas con la materia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 47. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o las Fiscales del Ministerio P\u00fablico en Defensa Ambiental:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer las atribuciones que esta Ley y el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> establecen para los o las Fiscales del Ministerio P\u00fablico de Proceso, cuando se est\u00e9 en presencia de presuntos hechos punibles que afecten el ambiente.<\/p><p>2.- Ejercer la acci\u00f3n civil derivada de los delitos ambientales, de conformidad con las leyes.<\/p><p>3.- Dirigir o realizar, seg\u00fan el caso, las investigaciones penales ambientales y las diligencias efectuadas por los \u00f3rganos policiales competentes; supervisar la legalidad de las actividades correspondientes y disponer todo lo referente a la adquisici\u00f3n y conservaci\u00f3n de los elementos de convicci\u00f3n.<\/p><p>4.- Solicitar ante el \u00f3rgano jurisdiccional competente las medidas precautelativas necesarias para eliminar un peligro, interrumpir la producci\u00f3n de da\u00f1os al ambiente o a las personas, o evitar las consecuencias degradantes del hecho que se investiga.<\/p><p>5.- Realizar, conforme a la ley y reglamentos correspondientes, servicios de guarder\u00eda ambiental.<\/p><p>6.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Octava<br>De los Fiscales o las Fiscales del Ministerio P\u00fablico con Competencia en Materia Ind\u00edgena<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 48. Definici\u00f3n.<\/strong> Son Fiscales del Ministerio P\u00fablico con Competencia en Materia Ind\u00edgena, aquellos o aquellas a quienes corresponda el ejercicio de las respectivas acciones o recursos, con ocasi\u00f3n de la violaci\u00f3n de los derechos y garant\u00edas constitucionales de los o las integrantes de los pueblos y comunidades ind\u00edgenas, en el curso de procedimientos administrativos, civiles o laborales.<\/p>\n\n\n\n<p><strong>Art\u00edculo 49. Requisitos.<\/strong> Para ser Fiscales del Ministerio P\u00fablico con Competencia en Materia Ind\u00edgena se requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ser ind\u00edgena y poseer suficientes conocimientos en la materia ind\u00edgena.<\/p><p>2.- Cumplir con los requisitos establecidos en el art\u00edculo 30 de esta Ley, con excepci\u00f3n de lo previsto en los numerales 2 y 9.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 50. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o las Fiscales del Ministerio P\u00fablico con Competencia en Materia Ind\u00edgena, los siguientes:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Intentar las acciones a que hubiere lugar para hacer efectiva la responsabilidad penal, civil o administrativa de las personas o instituciones, seg\u00fan sea el caso que, por acci\u00f3n u omisi\u00f3n, violen o amenacen los derechos colectivos o individuales de uno o m\u00e1s pueblos y comunidades ind\u00edgenas o de alguno de sus miembros.<\/p><p>2.- Investigar los hechos punibles cometidos con la participaci\u00f3n de ind\u00edgenas o en contra de \u00e9stos.<\/p><p>3.- Ejercer la acci\u00f3n penal, en los t\u00e9rminos y condiciones establecidos en la Ley que rige la materia y el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a>, preservando siempre la integridad cultural y los derechos reconocidos a los pueblos y comunidades ind\u00edgenas en la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y dem\u00e1s instrumentos legales nacionales e internacionales.<\/p><p>4.- Solicitar las medidas cautelares o la cesaci\u00f3n, modificaci\u00f3n o sustituci\u00f3n de las mismas o de las sanciones acordadas, procurando en caso de medida privativa de libertad, el cumplimiento de esta \u00faltima dentro del h\u00e1bitat ind\u00edgena.<\/p><p>5.- Interponer los recursos pertinentes de acuerdo con la ley.<\/p><p>6.- Recibir y tramitar las denuncias sobre infracciones de car\u00e1cter administrativo o civil contra ind\u00edgenas.<\/p><p>7.- Solicitar y aportar pruebas, y participar en su deposici\u00f3n conforme a lo previsto en la ley.<\/p><p>8.- Velar por el cumplimiento de las funciones de la polic\u00eda de investigaci\u00f3n y dem\u00e1s \u00f3rganos auxiliares de administraci\u00f3n de justicia.<\/p><p>9.- Asesorar a la victima y a los familiares de \u00e9sta durante la conciliaci\u00f3n, cuando as\u00ed le sea solicitado.<\/p><p>10.- Ejercer en general todas aquellas atribuciones que esta Ley y el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a> establecen para los Fiscales de Proceso, cuando se est\u00e9 en presencia de presuntos hechos punibles donde intervenga uno o m\u00e1s ind\u00edgenas.<\/p><p>11.- Las dem\u00e1s que les sean atribuidas por las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Secci\u00f3n Novena<br>De los Fiscales o las Fiscales Auxiliares del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 51. Definici\u00f3n.<\/strong> Son Fiscales Auxiliares del Ministerio P\u00fablico, aquellos o aquellas a quienes se les atribuye la funci\u00f3n de asistir a los fiscales o las fiscales principales del Ministerio P\u00fablico, a los cuales est\u00e1n subordinados funcionalmente.<\/p>\n\n\n\n<p><strong>Art\u00edculo 52. Requisitos.<\/strong> Para ser Fiscal Auxiliar del Ministerio P\u00fablico se requiere:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ser mayor de veinticinco arios de edad.<\/p><p>2.- Poseer suficientes conocimientos en materias jur\u00eddicas vinculadas con el ejercicio del cargo al cual va a optar.<\/p><p>3.- Cumplir con los requisitos establecidos en el art\u00edculo 30 de esta Ley, con excepci\u00f3n de lo previsto en los numerales 2, 9 y 10.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 53. Deberes y atribuciones.<\/strong> Son deberes y atribuciones de los Fiscales o las Fiscales Auxiliares del Ministerio P\u00fablico:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Realizar actuaciones de investigaci\u00f3n e intervenir en todos los actos de la fase preparatoria e intermedia del proceso penal.<\/p><p>2.- Intervenir en los procedimientos especiales establecidos en el <a href=\"copp.htm\">C\u00f3digo Org\u00e1nico Procesal Penal<\/a>, y dem\u00e1s leyes, salvo en los procedimientos en los juicios contra el Presidente o la Presidenta de la Rep\u00fablica o altos funcionarios o funcionarias del Estado y en los de extradici\u00f3n. En cuanto a la aplicaci\u00f3n del procedimiento abreviado, para la presentaci\u00f3n del aprehendido o aprehendida ante el juez o la jueza de control. solo podr\u00e1 actuar en caso de delitos flagrantes.<\/p><p>3.- Elaborar escritos, recursos o acciones judiciales.<\/p><p>4.- Revisar el estado de las causas en que est\u00e9 interviniendo el Ministerio P\u00fablico, y realizar las actuaciones correspondientes, dentro del \u00e1mbito de sus atribuciones.<\/p><p>5.- Rendir cuenta mensual al o la Fiscal Principal y en la oportunidad que este \u00faltimo o esta \u00faltima la requiera, de todas las actuaciones cumplidas.<\/p><p>6.- Intervenir en las acciones de amparo, referidas a la libertad y seguridad personal.<\/p><p>7.- Colaborar con el Fiscal o la Fiscal Principal en la supervisi\u00f3n del desempe\u00f1o del personal subalterno del despacho de adscripci\u00f3n.<\/p><p>8.- Las dem\u00e1s que les asignen las leyes o las resoluciones que dicte el Fiscal o la Fiscal General de Rep\u00fablica.<\/p><\/blockquote>\n\n\n\n<p><strong>Cap\u00edtulo V<br>Abogados Adjuntos o Abogadas Adjuntas<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 54. Abogados y abogadas adjuntos.<\/strong> El Ministerio P\u00fablico tendr\u00e1 a su servicio abogados adjuntos o abogadas adjuntas, quienes se considerar\u00e1n funcionarios o funcionarias de carrera, una vez que ingresen al Ministerio P\u00fablico por concurso. El Fiscal o la Fiscal General de la Rep\u00fablica o quien haga sus veces, cuando lo estime conveniente, dispondr\u00e1 la colaboraci\u00f3n de los abogados adscritos o las abogadas adscritas a una dependencia con cualquiera de las otras.<\/p>\n\n\n\n<p><strong>Cap\u00edtulo VI<br>De la Organizaci\u00f3n Municipal del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 55. Fiscal\u00edas a nivel Municipal.<\/strong> Las Fiscal\u00edas del Ministerio P\u00fablico a nivel municipal son aquellas cuya competencia territorial est\u00e9 atribuida a uno o m\u00e1s municipios. Estar\u00e1n adscritas a la Fiscal\u00eda Superior de la circunscripci\u00f3n judicial en donde est\u00e9 ubicado el o los municipios cuya competencia le corresponda.<\/p>\n\n\n\n<p><strong>Art\u00edculo 56. Competencia.<\/strong> Los Fiscales o las Fiscales del Ministerio P\u00fablico a nivel municipal tendr\u00e1n alguna de las siguientes atribuciones, seg\u00fan le sean asignadas por el Fiscal o la Fiscal General de la Rep\u00fablica:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Ejercer la acci\u00f3n penal en los casos de faltas y delitos cuyas penas no excedan de tres a\u00f1os en su l\u00edmite m\u00e1ximo, cometidos en el municipio dentro del cual puedan ejercer sus atribuciones.<\/p><p>2.- Velar por el debido proceso y la protecci\u00f3n de los derechos humanos y garant\u00edas constitucionales en todo lo relacionado con el \u00e1mbito municipal y la vida local.<\/p><\/blockquote>\n\n\n\n<p>Mientras no se le asigne a los Fiscales o las Fiscales con competencia a nivel municipal, la atribuci\u00f3n prevista en el numeral 1, la misma ser\u00e1 ejercida por el correspondiente Fiscal de Proceso.<\/p>\n\n\n\n<p><strong>T\u00edtulo IV<br>De las Faltas, Inhibiciones y Recusaciones<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 57. Faltas.<\/strong> Las faltas de los funcionarios o funcionarias del Ministerio P\u00fablico son absolutas, temporales y accidentales:<\/p>\n\n\n\n<p>1.- Constituyen faltas absolutas las que se produzcan por:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>a.- Muerte del funcionario o de la funcionaria.<\/p><p>b.- Cesaci\u00f3n en el ejercicio de sus funciones.<\/p><p>c.- Jubilaci\u00f3n.<\/p><p>d.- Destituci\u00f3n.<\/p><p>e.- Renuncia aceptada.<\/p><p>f.- Abandono del cargo.<\/p><p>g.- Anulaci\u00f3n de nombramiento.<\/p><p>h.- Enfermedad que lo o la incapacite para el ejercicio del cargo.<\/p><p>i.- Cualquier otro motivo que lo o la inhabilite para ejercer el cargo.<\/p><\/blockquote>\n\n\n\n<p>2.- Constituyen faltas temporales, la separaci\u00f3n del ejercicio del cargo en virtud de:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>a.- Licencia concedida.<\/p><p>b.- Vacaciones.<\/p><p>c.- Suspensi\u00f3n disciplinaria o por investigaci\u00f3n.<\/p><p>d.- Enfermedad que lo incapacite por un per\u00edodo inferior a dos a\u00f1os.<\/p><p>e.- Cualquier otra causa debidamente justificada que impida temporalmente el ejercicio de sus funciones.<\/p><\/blockquote>\n\n\n\n<p>3.- Constituye falta accidental, la separaci\u00f3n del ejercicio del cargo:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>a.- Por inhibici\u00f3n.<\/p><p>b.- Por recusaci\u00f3n.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 58. Fiscales suplentes.<\/strong> Las faltas temporales y absolutas de los Fiscales o las Fiscales titulares del Ministerio P\u00fablico ser\u00e1n cubiertas por sus suplentes, en el orden de su elecci\u00f3n. Agotada la lista de suplentes, el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, proceder\u00e1 a nombrar un o una suplente especial, quien deber\u00e1 cumplir con los mismos requisitos de elegibilidad previstos para el o la Fiscal titular.<\/p>\n\n\n\n<p>El o la suplente especial no podr\u00e1 ejercer ese cargo en tal condici\u00f3n por m\u00e1s de treinta d\u00edas continuos en el periodo de un a\u00f1o, a menos que la suplencia se haya motivado por enfermedad o reposo prenatal o postnatal. Las faltas accidentales se suplir\u00e1n con otro u otra Fiscal cuando en la circunscripci\u00f3n o circuito judicial respectivo hubiese m\u00e1s de un Fiscal o una Fiscal del Ministerio P\u00fablico. En caso contrario, el Fiscal o la Fiscal General de la Rep\u00fablica proceder\u00e1 a nombrar un suplente o una suplente especial, quien deber\u00e1 cumplir con los mismos requisitos de elegibilidad previstos para el o la Fiscal titular.<\/p>\n\n\n\n<p><strong>Art\u00edculo 59. Convocatoria.<\/strong> En caso de falta absoluta, la convocatoria del s\u00fapleme la har\u00e1 el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces; si la falta es temporal, la har\u00e1 el o la Fiscal titular.<\/p>\n\n\n\n<p><strong>Art\u00edculo 60. Aceptaci\u00f3n.<\/strong> Transcurridos tres d\u00edas h\u00e1biles sin que el primer o la primera suplente convocado o convocada concurra a manifestar expresamente su aceptaci\u00f3n, se convocar\u00e1 al segundo o segunda suplente de la lista respectiva, y en caso de que transcurridos tres d\u00edas h\u00e1biles contados a partir de la convocatoria, \u00e9ste o \u00e9sta no se presente o se excuse, el Fiscal o la Fiscal General de la Rep\u00fablica proceder\u00e1 a nombrar un o una suplente especial.<\/p>\n\n\n\n<p>Se considerar\u00e1 como excusa justificada la circunstancia comprobada de no encontrarse el o la suplente en el lugar donde debe residir el o la Fiscal, de acuerdo con lo previsto en esta Ley.<\/p>\n\n\n\n<p><strong>Art\u00edculo 61. Exclusi\u00f3n de suplentes.<\/strong> Los o las Suplentes que al ser convocados o convocadas en mis de dos ocasiones sucesivas no se encuentren en el lugar que sirve de sede a la correspondiente oficina del o la Fiscal, ser\u00e1n excluidos o excluidas de la lista respectiva. En igual forma se proceder\u00e1 despu\u00e9s de la tercera excusa, salvo que se funden en causas justificadas.<\/p>\n\n\n\n<p><strong>Art\u00edculo 62. Juramento.<\/strong> Los o las suplentes de los fiscales o las fiscales prestar\u00e1n juramento ante el o la Fiscal General de la Rep\u00fablica, o ante quien haga sus veces o ante la autoridad del Ministerio P\u00fablico que \u00e9ste o \u00e9sta designe.<\/p>\n\n\n\n<p><strong>Art\u00edculo 63. Inhibici\u00f3n o recusaci\u00f3n.<\/strong> Los fiscales o las fiscales del Ministerio P\u00fablico deber\u00e1n inhibirse o podr\u00e1n ser recusados o recusadas por las causales previstas en el articulo 65 de esta Ley.<\/p>\n\n\n\n<p><strong>Art\u00edculo 64. Inhibici\u00f3n.<\/strong> En caso de inhibici\u00f3n de un Fiscal o una fiscal del Ministerio P\u00fablico, \u00e9ste o \u00e9sta expondr\u00e1 por escrito ante el o la Fiscal Superior las razones de hecho y de derecho que la justifican. El o la fiscal Superior estar\u00e1 obligado u obligada a comunicar por la v\u00eda m\u00e1s r\u00e1pida al Fiscal o la Fiscal General de la Rep\u00fablica, o a quien haga sus veces, la solicitud y designar\u00e1 de inmediato a otro u otra Fiscal de la circunscripci\u00f3n judicial, conforme a lo previsto en las leyes respectivas. En caso de inhibici\u00f3n del Fiscal o la Fiscal Superior o de los dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico, la misma se plantear\u00e1 por ante el Fiscal o la Fiscal General de la Rep\u00fablica, o por quien haga sus veces, quien decidir\u00e1 lo pertinente.<\/p>\n\n\n\n<p>El designado o designada sustituir\u00e1 al inhibido o a la inhibida, a menos que tambi\u00e9n estuviere incurso en alguna causal de inhibici\u00f3n, caso en el cual se proceder\u00e1 de acuerdo con lo anterior.<\/p>\n\n\n\n<p>No podr\u00e1 obligarse al inhibido o a la inhibida a continuar interviniendo en el proceso, a menos que la solicitud sea declarada sin lugar o inadmisible.<\/p>\n\n\n\n<p><strong>Art\u00edculo 65. Procedencia de la Inhibici\u00f3n o Recusaci\u00f3n del o la Fiscal General de la Rep\u00fablica.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica deber\u00e1 inhibirse o podr\u00e1 ser recusado o recusada en los procesos judiciales o administrativos, cuando incurra en alguna de las causales siguientes:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Por parentesco de consanguinidad o de afinidad dentro del cuarto o segundo grado, respectivamente, con cualquiera de las partes o con el representante de alguna de ellas.<\/p><p>2.- Por parentesco de consanguinidad o de afinidad dentro del cuarto o segundo grado, respectivamente, con el c\u00f3nyuge de cualquiera de las partes o, en caso de tener hijos, con alguna de las partes aunque se encuentre divorciado o divorciada.<\/p><p>3.- Por ser padre o madre adoptante o, hijo adoptivo o hija adoptiva de alguna de las partes.<\/p><p>4.- Por tener amistad intima o enemistad manifiesta con alguna de las partes.<\/p><p>5.- Por tener su c\u00f3nyuge o alguno de sus parientes consangu\u00edneos o afines dentro de los grados mencionados en el numeral 1 de este articulo, inter\u00e9s directo en los resultados del proceso.<\/p><p>6.- Por haber emitido opini\u00f3n sobre la causa con conocimiento de ella.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 66. Causal excepcional.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica tambi\u00e9n podr\u00e1 inhibirse por cualquier otra causa, no contemplada en el articulo anterior, siempre que est\u00e9 fundada en motivos graves que afecten su imparcialidad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 67. Inadmisibilidad.<\/strong> Es inadmisible la recusaci\u00f3n que se intente sin expresar los motivos en que se funde. Igualmente la que se proponga despu\u00e9s de transcurridos cinco d\u00edas h\u00e1biles, contados a partir de la presentaci\u00f3n de la querella o de la acusaci\u00f3n, seg\u00fan el caso.<\/p>\n\n\n\n<p><strong>Art\u00edculo 68. Procedimiento.<\/strong> Declarada la admisibilidad de la recusaci\u00f3n, el Fiscal o la Fiscal General de la Rep\u00fablica deber\u00e1, dentro de los cinco d\u00edas h\u00e1biles siguientes, informar al Tribunal Supremo de Justicia sobre la pertinencia de la incidencia propuesta.<\/p>\n\n\n\n<p>El funcionario o la funcionaria que conozca de la recusaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica, abrir\u00e1 una articulaci\u00f3n por tres d\u00edas para promover y evacuar las pruebas aportadas por las partes, sin conceder en ning\u00fan caso, el t\u00e9rmino de la distancia, y resolver\u00e1 el procedimiento dentro de los cinco d\u00edas h\u00e1biles siguientes.<\/p>\n\n\n\n<p><strong>Art\u00edculo 69. Continuidad.<\/strong> La recusaci\u00f3n del Fiscal o la Fiscal General de la Rep\u00fablica no detendr\u00e1 el curso del proceso, cuyo conocimiento pasar\u00e1 de manera inmediata al funcionario o funcionaria que deba sustituirle conforme a esta ley, hasta tanto se decida la incidencia.<\/p>\n\n\n\n<p><strong>Art\u00edculo 70. Conclusi\u00f3n del procedimiento.<\/strong> Se declarar\u00e1 concluido el procedimiento si el Fiscal o la Fiscal General de la Rep\u00fablica manifiesta su inhibici\u00f3n despu\u00e9s de haber sido recusado o recusada.<\/p>\n\n\n\n<p><strong>Art\u00edculo 71. Constancia de inhibici\u00f3n.<\/strong> Cuando el Fiscal o la Fiscal General de la Rep\u00fablica se inhiba de seguir conociendo de una causa determinada, se har\u00e1 constar en el expediente respectivo su decisi\u00f3n y continuar\u00e1 conociendo el funcionario o funcionaria a quien corresponda actuar.<\/p>\n\n\n\n<p><strong>Art\u00edculo 72. Limite.<\/strong> Las partes no podr\u00e1n intentar en una misma causa m\u00e1s de dos recusaciones contra el Fiscal o la Fiscal General de la Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 73. Improcedencia del recurso.<\/strong> Contra las decisiones que se dicten en las incidencias de recusaci\u00f3n contra el Fiscal o la Fiscal General de la Rep\u00fablica no proceder\u00e1 recurso alguno.<\/p>\n\n\n\n<p><strong>Art\u00edculo 74. Procedimiento.<\/strong> La recusaci\u00f3n podr\u00e1 ser presentada por las personas legitimadas para recusar, en la oportunidad procesal correspondiente, ante el o la Fiscal Superior, por escrito razonado, con indicaci\u00f3n de las causales en las cuales se fundamente.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal Superior estar\u00e1 obligado u obligada a informar por la v\u00eda m\u00e1s r\u00e1pida al o a la Fiscal General de la Rep\u00fablica, o por quien haga sus veces, la recusaci\u00f3n propuesta y designar\u00e1 a otro u otra Fiscal de la circunscripci\u00f3n judicial, conforme a lo previsto en esta Ley.<\/p>\n\n\n\n<p>Si el recusado o recusada es el Fiscal o la Fiscal Superior, la recusaci\u00f3n ser\u00e1 presentada en la misma forma ante el Fiscal o la Fiscal General de Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 75. Conocimiento.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, conocer\u00e1 y decidir\u00e1 las incidencias de recusaci\u00f3n y de inhibici\u00f3n de los o las fiscales y funcionarios o funcionarias del Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>Art\u00edculo 76. Impugnaci\u00f3n.<\/strong> El funcionario o la funcionaria del Ministerio P\u00fablico recusado o recusada expondr\u00e1 por escrito, dentro de un lapso no mayor de cinco d\u00edas h\u00e1biles, contados a partir del momento de su notificaci\u00f3n, ante el o la Fiscal General de la Rep\u00fablica, o por quien haga sus veces, o ante el Fiscal o la Fiscal Superior, seg\u00fan el caso, las razones de hecho y de derecho que tenga para impugnar la recusaci\u00f3n, sin perjuicio de la continuaci\u00f3n del procedimiento.<\/p>\n\n\n\n<p>Recibida la impugnaci\u00f3n, el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, decidir\u00e1 en el lapso de tres d\u00edas si admite o no la recusaci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 77. Tramitaci\u00f3n.<\/strong> Se declarar\u00e1 inadmisible la recusaci\u00f3n y concluido el procedimiento si no est\u00e1 fundada en alguna de las causales de recusaci\u00f3n. Tambi\u00e9n se declarar\u00e1 concluido el procedimiento, si el Fiscal o la Fiscal o el funcionario o la funcionaria manifiesta su inhibici\u00f3n despu\u00e9s de haber sido recusado o recusada. Declarada la admisibilidad, se abrir\u00e1 una articulaci\u00f3n por cinco d\u00edas, para promover y evacuar las pruebas. El procedimiento se resolver\u00e1 al d\u00e9cimo d\u00eda, sin conceder en ning\u00fan caso, el t\u00e9rmino de la distancia.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, resolver\u00e1 sin esperar el vencimiento del termino de la articulaci\u00f3n probatoria, cuando la incidencia pueda resolverse con las pruebas ya producidas en dicha articulaci\u00f3n o cuando las partes renuncien al derecho de promover otras.<\/p>\n\n\n\n<p><strong>Art\u00edculo 78. Continuidad.<\/strong> El proceso no se paralizar\u00e1 por incidencias de recusaciones ni inhibiciones, y seguir\u00e1 su curso con la intervenci\u00f3n de otro funcionario o funcionaria que al efecto haya designado el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, o el Fiscal o la Fiscal Superior.<\/p>\n\n\n\n<p><strong>Art\u00edculo 79. Multa.<\/strong> Si la recusaci\u00f3n fuere declarada inadmisible o sin lugar, o si hubiere desistimiento, el recusante o la recusante pagar\u00e1 una multa en bol\u00edvares equivalente de veinte unidades tributarias (20 U.T.) a cincuenta unidades tributarias (50 U.T.); si la recusaci\u00f3n fuere formulada de mala fe, se le impondr\u00e1 una multa de cincuenta unidades tributarias (50 U.T.) a cien unidades tributarias (100 U.T.). Si el recusante o la recusante no acredita haber pagado la multa dentro del tercer d\u00eda h\u00e1bil siguiente a su notificaci\u00f3n, se le impondr\u00e1 dentro de los diez d\u00edas h\u00e1biles siguientes, hasta dos multas sucesivas, cada una por el doble de la ya impuesta. Si persiste la contumacia, el Ministerio P\u00fablico podr\u00e1 acudir a la v\u00eda judicial para obtener la cancelaci\u00f3n correspondiente. A tales efectos, las multas impuestas se considerar\u00e1n cr\u00e9ditos fiscales.<\/p>\n\n\n\n<p><strong>Art\u00edculo 80. Sanci\u00f3n.<\/strong> Declarada con lugar la recusaci\u00f3n, el Fiscal o la Fiscal General de la Rep\u00fablica podr\u00e1 sancionar al o a la funcionaria que infringi\u00f3 el deber de inhibirse, con suspensi\u00f3n o destituci\u00f3n del ejercicio del cargo, seg\u00fan la gravedad de las circunstancias que dieron motivo a la recusaci\u00f3n, previa apertura del procedimiento administrativo correspondiente, cuya sustanciaci\u00f3n y decisi\u00f3n no podr\u00e1 exceder de diez d\u00edas h\u00e1biles.<\/p>\n\n\n\n<p>El o la recusante tiene derecho a solicitar al Fiscal o la Fiscal General de la Rep\u00fablica, o a quien haga sus veces, la aplicaci\u00f3n de la referida sanci\u00f3n disciplinaria.<\/p>\n\n\n\n<p><strong>T\u00edtulo V<br>De los Deberes, Prohibiciones y Derechos de los Funcionarios o las Funcionarias del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Cap\u00edtulo I<br>Ejercicio del cargo<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 81. Juramentaci\u00f3n.<\/strong> Los fiscales o las fiscales y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico, as\u00ed como los delegados o delegadas especiales, antes de entrar en el ejercicio de sus funciones, prestar\u00e1n juramento de cumplir fielmente la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a>, las leyes y los deberes inherentes al cargo ante el Fiscal o la Fiscal General de la Rep\u00fablica o la autoridad del Ministerio P\u00fablico que \u00e9ste o \u00e9sta designe. En este \u00faltimo caso, del acta de juramentaci\u00f3n se remitir\u00e1 copia certificada al Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces.<\/p>\n\n\n\n<p><strong>Art\u00edculo 82. Inventario.<\/strong> Los fiscales o las fiscales y dem\u00e1s funcionarios o funcionarias que tengan a su cargo una dependencia, al tomar posesi\u00f3n del cargo y al cesar definitivamente en sus funciones, deber\u00e1n recibir o entregar la oficina, mediante un acta, y elaborar, adem\u00e1s, seg\u00fan el caso, un inventario, un estado de las cuentas y un \u00edndice del archivo, de los libros, documentos y expedientes que demuestren el estado general de la dependencia. El funcionario o la funcionaria entrante tendr\u00e1 derecho a formular las observaciones que considere pertinentes al acta de entrega y a los respaldos que la conforman, dentro de los noventa d\u00edas siguientes a la recepci\u00f3n de la dependencia. De dicha acta se remitir\u00e1 un ejemplar al \u00f3rgano auditor interno, otro a la Direcci\u00f3n de Administraci\u00f3n y se conservar\u00e1 un tercero en la oficina respectiva.<\/p>\n\n\n\n<p><strong>Art\u00edculo 83. Residencia.<\/strong> Los fiscales o las fiscales del Ministerio P\u00fablico residir\u00e1n en el lugar del ejercicio de sus atribuciones o en el \u00e1rea suburbana inmediata.<\/p>\n\n\n\n<p>S\u00f3lo podr\u00e1n ausentarte por algunas de las causales constitutivas de faltas temporales, conforme al art\u00edculo 57 de esta Ley y por razones de servicio debidamente justificadas y autorizadas por el Fiscal o la Fiscal Superior. Las autorizaciones que al respecto requieran los fiscales o las fiscales superiores ser\u00e1n otorgadas por el director o directora de adscripci\u00f3n.<\/p>\n\n\n\n<p>Si se ausentaren sin existir alguna de las circunstancias anteriores, podr\u00e1n ser sancionados o sancionadas disciplinariamente por el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, de conformidad con lo dispuesto en el Titulo IX de esta Ley.<\/p>\n\n\n\n<p><strong>Art\u00edculo 84. Asistencia.<\/strong> Los fiscales o las fiscales o funcionarios o funcionarias del Ministerio P\u00fablico deber\u00e1n concurrir a su oficina los d\u00edas laborables, cuando est\u00e9n de guardia o sean requeridos por razones de servicio.<\/p>\n\n\n\n<p><strong>Art\u00edculo 85. Actuaciones.<\/strong> Los fiscales o las fiscales del Ministerio P\u00fablico llevar\u00e1n un registro donde har\u00e1n constar sus actuaciones diarias, el cual firmar\u00e1n cada d\u00eda al finalizar su labor, salvo casos de fuerza mayor.<\/p>\n\n\n\n<p><strong>Art\u00edculo 86. Informe.<\/strong> Los fiscales o las fiscales del Ministerio P\u00fablico presentar\u00e1n mensualmente al Despacho del Fiscal o la Fiscal General de la Rep\u00fablica, o por quien haga sus veces, un informe de sus actividades; y en Los primeros quince d\u00edas del mes de enero de cada a\u00f1o, un resumen de las actividades del a\u00f1o anterior y las observaciones y sugerencias que consideren \u00fatiles para el mejoramiento del servicio y de la administraci\u00f3n de justicia. Los fiscales o las fiscales del Ministerio P\u00fablico presentar\u00e1n dichos informes a trav\u00e9s de los o las fiscales superiores de la circunscripci\u00f3n judicial respectiva. Cuando se trate de los o las fiscales superiores se presentar\u00e1 ante su direcci\u00f3n de adscripci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 87. Incompatibilidad.<\/strong> Los cargos de los funcionarios o funcionarias del Ministerio P\u00fablico son incompatibles con el desempe\u00f1o de cualquier otro cargo, profesi\u00f3n o actividad p\u00fablica o privada, excepto las acad\u00e9micas, accidentales, asistenciales o docentes. Corresponde al Fiscal o a la Fiscal General de la Rep\u00fablica valorar y apreciar tales circunstancias. La designaci\u00f3n en el cargo accidental de Delegado o Delegada Especial, no inhabilita a la persona para el libre ejercicio de la profesi\u00f3n de abogado o abogada.<\/p>\n\n\n\n<p><strong>Art\u00edculo 88. Abstenci\u00f3n.<\/strong> Los funcionarios o funcionarias del Ministerio P\u00fablico se abstendr\u00e1n de adelantar opini\u00f3n no autorizada respecto de los asuntos que est\u00e9n llamados a conocer.<\/p>\n\n\n\n<p><strong>Art\u00edculo 89. Prohibici\u00f3n.<\/strong> Los funcionarios o funcionarias del Ministerio P\u00fablico no podr\u00e1n separarse del ejercicio del cargo, sino por motivos debidamente justificados y mediante licencia. En ning\u00fan caso podr\u00e1n hacerlo antes de que el sustituto tome posesi\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 90. Licencia.<\/strong> Los funcionarios o funcionarias del Ministerio P\u00fablico tienen derecho a licencias, cuyo r\u00e9gimen se regir\u00e1 por lo establecido en el Estatuto de Personal del Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>Art\u00edculo 91. Vacaciones.<\/strong> Los funcionarios o funcionarias del Ministerio P\u00fablico tendr\u00e1n derecho al disfrute de vacaciones anuales remuneradas, en la siguiente proporci\u00f3n: Durante los primeros cinco a\u00f1os de servicios, gozar\u00e1n de treinta d\u00edas continuos, de seis a diez a\u00f1os de servicios, gozar\u00e1n de cuarenta d\u00edas continuos; y por m\u00e1s de diez a\u00f1os de servicios, gozar\u00e1n de cuarenta y cinco d\u00edas continuos. Estos lapsos podr\u00e1n modificarse en beneficio de los funcionarios o las funcionarias del Ministerio P\u00fablico cuando as\u00ed lo decida el Fiscal o la Fiscal General de la Rep\u00fablica o cuando el Ejecutivo Nacional introduzca modificaciones al r\u00e9gimen de vacaciones de sus funcionarios, siempre que \u00e9ste sea m\u00e1s favorable que el establecido para el organismo.<\/p>\n\n\n\n<p><strong>Art\u00edculo 92. Jubilaci\u00f3n.<\/strong> Los fiscales o las fiscales y los funcionarios o funcionarias del Ministerio P\u00fablico tienen derecho a la seguridad social, de acuerdo con los t\u00e9rminos y condiciones establecidos en la <a href=\"losss.htm\">Ley Org\u00e1nica del Sistema de Seguridad Social<\/a> y dem\u00e1s leyes que regulan la materia.<\/p>\n\n\n\n<p><strong>T\u00edtulo VI<br>R\u00e9gimen de la Carrera y Concurso<\/strong><\/p>\n\n\n\n<p><strong>Cap\u00edtulo I<br>De la Carrera del Funcionario o Funcionaria del Ministerio P\u00fablico<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 93. Regulaci\u00f3n.<\/strong> Se crea la carrera del funcionario o funcionaria del Ministerio P\u00fablico, cuyas normas sobre el ingreso, ascenso, traslado, suspensi\u00f3n, estabilidad y retiro, se regir\u00e1n por las disposiciones de la presente Ley y del Estatuto de Personal del Ministerio P\u00fablico.<\/p>\n\n\n\n<p><strong>Art\u00edculo 94. Del ingreso.<\/strong> Para ingresar a la carrera se requiere aprobar un concurso p\u00fablico de credenciales y de oposici\u00f3n.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal General de la Rep\u00fablica, mediante resoluci\u00f3n, establecer\u00e1 las bases y requisitos del concurso, con arreglo a lo dispuesto en esta Ley.<\/p>\n\n\n\n<p><strong>Art\u00edculo 95. Del ascenso.<\/strong> Se considerar\u00e1 ascenso la promoci\u00f3n de un funcionario o funcionaria titular de un cargo a otro de nivel superior. Sin perjuicio de lo establecido para el ingreso a los diferentes cargos de Fiscal del Ministerio P\u00fablico, los funcionarios o las funcionarias de carrera tendr\u00e1n derecho al ascenso, siempre que haya un cargo vacante, el cual se otorgar\u00e1 de acuerdo con la evaluaci\u00f3n de su rendimiento y desempe\u00f1o, cumplimiento de tas normas internas de personal, constancias de actualizaci\u00f3n profesional y antig\u00fcedad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 96. De la reclasificaci\u00f3n de cargo.<\/strong> Los funcionarios o funcionarias de carrera del Ministerio P\u00fablico tendr\u00e1n derecho a solicitar, a trav\u00e9s de su superior inmediato, una reclasificaci\u00f3n del cargo que ocupen, la cual ser\u00e1 analizada por la Direcci\u00f3n de Recursos Humanos dentro del lapso de los treinta d\u00edas siguientes al recibo de la solicitud. La reclasificaci\u00f3n proceder\u00e1, siempre que exista la necesidad institucional, la disponibilidad presupuestaria que se requiera y el solicitante cumpla con los requisitos exigidos para el cargo al cual aspira ser reclasificado; tambi\u00e9n deber\u00e1 tomarse en consideraci\u00f3n su rendimiento y desempe\u00f1o, cumplimiento de las normas internas de personal y constancia de actualizaci\u00f3n profesional.<\/p>\n\n\n\n<p>Si la Direcci\u00f3n de Recursos Humanos no diere respuesta a la solicitud de reclasificaci\u00f3n de cargo, dentro del lapso aqu\u00ed previsto, se entender\u00e1 que la misma fue negada.<\/p>\n\n\n\n<p><strong>Art\u00edculo 97. Del traslado.<\/strong> Los funcionarios o funcionarias del Ministerio P\u00fablico podr\u00e1n ser trasladados por razones de servicio, mediante resoluci\u00f3n motivada del Fiscal o la Fiscal General de la Rep\u00fablica o por quien haga sus veces, de un cargo a otro cargo de la misma clase y para el cual cumpla con los requisitos exigidos para el mismo, siempre que no se disminuya su sueldo b\u00e1sico y los complementos que les puedan corresponder.<\/p>\n\n\n\n<p><strong>Art\u00edculo 98. Causa de los traslados.<\/strong> Los traslados de los funcionarios o funcionarias del Ministerio P\u00fablico podr\u00e1n realizarse:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Por solicitud del funcionario o funcionaria, en el cual indique los motivos de su petici\u00f3n.<\/p><p>2.- Por razones de servicio, debidamente justificadas.<\/p><\/blockquote>\n\n\n\n<p><strong>Cap\u00edtulo II<br>Concursos<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 99. Convocatoria del Concurso.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica convocar\u00e1 a un concurso p\u00fablico de credenciales y de oposici\u00f3n para la provisi\u00f3n de los cargos de fiscales del Ministerio P\u00fablico y sus suplentes, mediante resoluci\u00f3n que se publicar\u00e1 dos veces en un peri\u00f3dico de circulaci\u00f3n nacional, con un intervalo de tres d\u00edas continuos entre una y otra publicaci\u00f3n. Dichas publicaciones deber\u00e1n indicar el cargo a proveerse mediante concurso, la circunscripci\u00f3n judicial en la cual deber\u00e1 desempe\u00f1arse el mismo, el articulo o art\u00edculos de la Ley Org\u00e1nica del Ministerio P\u00fablico contentivos de los requisitos de elegibilidad del cargo objeto de concurso, los documentos que deben adjuntarse a la inscripci\u00f3n, la fecha l\u00edmite para consignarlos y el lugar donde debe procederse a la inscripci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 100. Integraci\u00f3n del jurado.<\/strong> El jurado de los concursos estar\u00e1 integrado por:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, o el funcionario o la funcionaria del Ministerio P\u00fablico que \u00e9ste o \u00e9sta designe al efecto, quien deber\u00e1 tener como m\u00ednimo diez a\u00f1os en el Ministerio P\u00fablico y especializaci\u00f3n en la materia objeto del concurso.<\/p><p>2.- El Vicefiscal o la Vicefiscal y un Director General del \u00e1rea jur\u00eddica.<\/p><p>3.- Dos profesores universitarios en ciencia jur\u00eddica con categor\u00eda de profesor o profesora titular en la materia objeto del concurso, o dos juristas de reconocida competencia con un m\u00ednimo de quince a\u00f1os de graduados y especializaci\u00f3n en la materia jur\u00eddica.<\/p><\/blockquote>\n\n\n\n<p>Los integrantes del jurado deber\u00e1n ser de notoria buena conducta y de reconocida solvencia moral.<\/p>\n\n\n\n<p>Cada miembro del jurado Tendr\u00e1 dos suplentes, quienes cubrir\u00e1n sus faltas absolutas, temporales y accidentales, en el orden de su designaci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 101. Convocatoria del jurado.<\/strong> La convocatoria del jurado la har\u00e1 el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, con diez d\u00edas h\u00e1biles de anticipaci\u00f3n a la oportunidad de la recepci\u00f3n de las credenciales de los o las aspirantes.<\/p>\n\n\n\n<p>El convocado o convocada manifestar\u00e1 su aceptaci\u00f3n o excusa, dentro de los cinco d\u00edas h\u00e1biles siguientes a la fecha de su convocatoria.<\/p>\n\n\n\n<p><strong>Art\u00edculo 102. Evaluaciones.<\/strong> El concurso para optar al cargo de Fiscal del Ministerio P\u00fablico estar\u00e1 integrado por tres pruebas de car\u00e1cter p\u00fablico, eliminatorias y sucesivas, que se desarrollar\u00e1n de acuerdo con lo establecido en la presente Ley y en la resoluci\u00f3n que al efecto dicte el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces. Las referidas pruebas y su orden de aplicaci\u00f3n es el siguiente:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Evaluaci\u00f3n de credenciales.<\/p><p>2.- Prueba escrita.<\/p><p>3.- Prueba oral.<\/p><\/blockquote>\n\n\n\n<p>La aptitud psicol\u00f3gica se evaluar\u00e1 una vez concluida la prueba de credenciales a aquellos aspirantes preseleccionados y su resultado se expresar\u00e1 en un informe de car\u00e1cter t\u00e9cnico que se le entregar\u00e1 al jurado para su debida evaluaci\u00f3n.<\/p>\n\n\n\n<p>Esta prueba tendr\u00e1 car\u00e1cter confidencial y ser\u00e1 efectuada por un equipo conformado por profesionales de la psiquiatr\u00eda o la psicolog\u00eda en un n\u00famero impar no menor de tres, designado por el Fiscal o la Fiscal General de la Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 103. Comisi\u00f3n para la elaboraci\u00f3n del baremo.<\/strong> El baremo de evaluaci\u00f3n de los o las aspirantes a ingresar al Ministerio P\u00fablico ser\u00e1 elaborado por una comisi\u00f3n de cinco funcionarios del Ministerio P\u00fablico, designados por el Fiscal o la Fiscal General de la Rep\u00fablica, de los cuales tres de ellos deber\u00e1n ser profesionales del derecho, con un m\u00ednimo de ocho a\u00f1os en la instituci\u00f3n.<\/p>\n\n\n\n<p>Los o las integrantes de la comisi\u00f3n deber\u00e1n ser de notoria buena conducta y de reconocida solvencia moral.<\/p>\n\n\n\n<p>La comisi\u00f3n contar\u00e1 con dos asesores en materia de elaboraci\u00f3n de baremo.<\/p>\n\n\n\n<p><strong>Art\u00edculo 104. Baremo de credenciales.<\/strong> El baremo de credenciales deber\u00e1 ajustarse a las normas usuales sobre evaluaci\u00f3n de credenciales; contar\u00e1 con todas las especificaciones t\u00e9cnicas y legales exigidas para los cargos sometidos a los concursos correspondientes y ser\u00e1 aprobado por el Fiscal o la Fiscal General de la Rep\u00fablica mediante resoluci\u00f3n que se publicar\u00e1 en la Gaceta Oficial de la Rep\u00fablica Bolivariana de Venezuela.<\/p>\n\n\n\n<p>Una vez efectuada la convocatoria p\u00fablica del respectivo concurso, el baremo aplicable para ese momento no se podr\u00e1 variar.<\/p>\n\n\n\n<p>En la convocatoria al concurso se deber\u00e1n especificar los datos sobre la publicaci\u00f3n del baremo.<\/p>\n\n\n\n<p><strong>Art\u00edculo 105. Evaluaci\u00f3n de credenciales.<\/strong> Concluida la recepci\u00f3n de credenciales, el jurado proceder\u00e1 a su evaluaci\u00f3n, de conformidad con las reglas establecidas en el baremo. Los o las aspirantes que aprueben la evaluaci\u00f3n de credenciales con una calificaci\u00f3n igual o superior al setenta y cinco por ciento del puntaje establecido mediante resoluci\u00f3n, deber\u00e1n presentar la prueba psicol\u00f3gica y, de resultar elegibles, podr\u00e1n presentar la prueba escrita.<\/p>\n\n\n\n<p><strong>Art\u00edculo 106. Prueba escrita.<\/strong> La prueba escrita versar\u00e1 sobre el contenido de los temas del programa de concurso establecidos mediante resoluci\u00f3n que dicte el Fiscal o la Fiscal General de la Rep\u00fablica, y tendr\u00e1 como prop\u00f3sito apreciar la formaci\u00f3n acad\u00e9mica del o de la aspirante, su dominio de la materia relacionada con el cargo para el cual opte, lenguaje escrito, capacidad de an\u00e1lisis y de s\u00edntesis de problemas relacionados con el desempe\u00f1o de las funciones inherentes al cargo para el cual opta.<\/p>\n\n\n\n<p>Para aprobar la prueba escrita, los o las aspirantes deber\u00e1n obtener una calificaci\u00f3n igual o superior al setenta y cinco por ciento de la escala de puntuaci\u00f3n establecida en la resoluci\u00f3n que dicte el Fiscal o la Fiscal General de la Rep\u00fablica. Los o las aspirantes que aprueben la prueba escrita, quedar\u00e1n seleccionados o seleccionadas para presentar la prueba oral.<\/p>\n\n\n\n<p><strong>Art\u00edculo 107. Publicaci\u00f3n de los resultados de las pruebas.<\/strong> La lista de los o las aspirantes que hayan aprobado la prueba de credenciales y la escrita se publicar\u00e1 en un peri\u00f3dico de circulaci\u00f3n nacional y en la p\u00e1gina Web del Ministerio P\u00fablico, indic\u00e1ndose en la misma el d\u00eda, lugar y hora en que se celebrar\u00e1 la siguiente prueba.<\/p>\n\n\n\n<p><strong>Art\u00edculo 108. Prueba Oral.<\/strong> La prueba oral consistir\u00e1 en la realizaci\u00f3n de una evaluaci\u00f3n p\u00fablica a los o a las aspirantes preseleccionados o preseleccionadas, y tendr\u00e1 como finalidad examinar sus conocimientos jur\u00eddicos, su capacidad de oratoria, as\u00ed como su habilidad para desarrollar un tema seleccionado al azar por el o la aspirante, entre aquellos contemplados en el programa del concurso.<\/p>\n\n\n\n<p>La prueba oral se aprobar\u00e1 con una calificaci\u00f3n igual o superior al setenta y cinco por ciento de la puntuaci\u00f3n establecida mediante resoluci\u00f3n que dicte el Fiscal o la Fiscal General de la Rep\u00fablica.<\/p>\n\n\n\n<p><strong>Art\u00edculo 109. Ganador o ganadora del concurso.<\/strong> Se designar\u00e1 en el cargo objeto del concurso, al o a la aspirante que hubiere obtenido mayor nota final, como resultado del promedio de las pruebas efectuadas.<\/p>\n\n\n\n<p>Ser\u00e1n designados o designadas como primer o primera y segundo o segunda suplente, respectivamente, aquellos o aquellas aspirantes que hayan obtenido la segunda y tercera mejor calificaci\u00f3n como resultado final.<\/p>\n\n\n\n<p><strong>Art\u00edculo 110. Publicaci\u00f3n del Veredicto.<\/strong> El veredicto del concurso se publicar\u00e1 en un peri\u00f3dico de circulaci\u00f3n nacional y en la p\u00e1gina Web del Ministerio P\u00fablico dentro de los cinco d\u00edas siguientes, contados a partir de su emisi\u00f3n por el jurado.<\/p>\n\n\n\n<p><strong>Art\u00edculo 111. Revocatoria de la designaci\u00f3n.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, revocar\u00e1 la designaci\u00f3n de aquel o aquella Fiscal del Ministerio P\u00fablico ganador o ganadora del concurso, o de los o las suplentes designados o designadas de igual forma, si se demostrare que hubiere forjado documentos o suministrado informaci\u00f3n falsa para participar en el mismo, sin perjuicio de otras responsabilidades a que haya lugar.<\/p>\n\n\n\n<p><strong>Art\u00edculo 112. Prohibici\u00f3n.<\/strong> Los o las aspirantes que hubieren obtenido una nota final inferior al setenta y cinco por ciento, de acuerdo con la escala de puntuaci\u00f3n establecida en la resoluci\u00f3n que dicte el Fiscal o la Fiscal General de la Rep\u00fablica, o quien haga sus veces, no podr\u00e1n inscribirse en un concurso para la provisi\u00f3n de un cargo de igual jerarqu\u00eda y con las mismas atribuciones y deberes, hasta que haya transcurrido un lapso de un a\u00f1o.<\/p>\n\n\n\n<p><strong>Art\u00edculo 113. Impugnaci\u00f3n.<\/strong> Quien se postule al cargo de Fiscal del Ministerio P\u00fablico podr\u00e1 ser impugnado durante el proceso de oposici\u00f3n antes de la realizaci\u00f3n de la prueba oral. Quien impugne deber\u00e1 consignar pruebas fehacientes y argumentos sustanciales de su impugnaci\u00f3n.<\/p>\n\n\n\n<p><strong>Art\u00edculo 114. Descargo.<\/strong> El postulada o postulada al cargo de Fiscal del Ministerio P\u00fablico har\u00e1 el descargo a la impugnaci\u00f3n en su contra o durante la presentaci\u00f3n de la prueba oral en la que adem\u00e1s presentar\u00e1 informe escrito de sus al\u00e9galos y pruebas ante la impugnaci\u00f3n, las cuales ser\u00e1n evaluadas por el jurado calificador, quien decidir\u00e1 sobre su procedencia o no, antes de lo previsto en el articulo 109 de esta Ley.<\/p>\n\n\n\n<p><strong>T\u00edtulo VII<br>R\u00e9gimen Presupuestario<\/strong><\/p>\n\n\n\n<p><strong>Cap\u00edtulo I<br>Presupuesto<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 115. Elaboraci\u00f3n de presupuesto.<\/strong> El Ministerio P\u00fablico estar\u00e1 sujeto a las leyes y reglamentos sobre la elaboraci\u00f3n y ejecuci\u00f3n del presupuesto, en cuanto le sean aplicables. No obstante, a los efectos de garantizar la autonom\u00eda presupuestaria en el ejercicio de sus atribuciones, regir\u00e1n las siguientes disposiciones especiales para la elaboraci\u00f3n y ejecuci\u00f3n de su presupuesto:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- El Ministerio P\u00fablico preparar\u00e1 cada a\u00f1o su proyecto de presupuesto de gastos, el cual ser\u00e1 remitido al Ejecutivo Nacional para su incorporaci\u00f3n al correspondiente Proyecto de Ley de Presupuesto que se someter\u00e1 a la consideraci\u00f3n de la Asamblea Nacional.<\/p><p>2.- La ejecuci\u00f3n del presupuesto del Ministerio P\u00fablico est\u00e1 sujeta a los controles previstos en las leyes.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 116. Ejecuci\u00f3n.<\/strong> El Fiscal o la Fiscal General de la Rep\u00fablica celebrar\u00e1 los contratos y ser\u00e1 el ordenador u ordenadora de pago, a los fines de la ejecuci\u00f3n del presupuesto del Ministerio P\u00fablico.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal General de la Rep\u00fablica podr\u00e1 delegar estas facultades, de conformidad con lo dispuesto en esta Ley y en la normativa legal que rige la materia.<\/p>\n\n\n\n<p><strong>T\u00edtulo VIII<br>De las Sanciones Administrativas y Disciplinarias<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 117. Causales.<\/strong> Los fiscales o las fiscales y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico, previo el debido proceso, podr\u00e1n ser sancionados disciplinariamente por el Fiscal o la Fiscal General de la Rep\u00fablica, sin perjuicio de la responsabilidad por los delitos o faltas en que incurran:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Por ofender de palabra, por escrito o de obra a sus superiores jer\u00e1rquicos, iguales o subalternos; falta a las consideraciones debidas al personal y traspasar los limites racionales de su autoridad respecto a sus auxiliares y subalternos o a los ciudadanos y ciudadanas que acudan a solicitar los servicios de su ministerio.<\/p><p>2.- Cuando incumplan el horario establecido o se ausenten del lugar donde ejerzan sus funciones en tiempo h\u00e1bil y en forma injustificada, sin la licencia respectiva.<\/p><p>3.- Cuando contraigan obligaciones que den lugar a reclamaciones judiciales en las que fueren declarados responsables.<\/p><p>4.- Cuando observen una conducta censurable que comprometa la dignidad del cargo o le hagan desmerecer en el concepto p\u00fablico.<\/p><p>5.- Cuando soliciten o reciban d\u00e1divas, pr\u00e9stamos, regalos o cualquiera otra clase de lucro de alguna de las partes, apoderados o terceros.<\/p><p>6.- Cuando realicen actos propios del libre ejercicio de la profesi\u00f3n de abogado.<\/p><p>7.- Cuando realicen actividad pol\u00edtico-partidista de cualquier naturaleza durante el ejercicio de sus funciones.<\/p><p>8.- Cuando propicien, auspicien u organicen huelgas, paros, suspensi\u00f3n total o parcial de actividades o disminuci\u00f3n del ritmo de trabajo o participen en tales actos o los toleren.<\/p><p>9.- Cuando incurran en abuso o exceso de autoridad.<\/p><p>10.- Por incumplimiento o negligencia en el ejercicio de sus deberes.<\/p><p>11.- Por denuncias de ciudadanos y ciudadanas se aprueba el retardo procesal en juicio bajo su responsabilidad y sea imputable a la conduc\u00eda del Fiscal o la Fiscal del Ministerio P\u00fablico.<\/p><p>12.- Cuando se revele expresamente la confidencialidad y reserva de la documentaci\u00f3n y los asuntos determinados como tales en los art\u00edculos 115 y 121 de esta Ley.<\/p><\/blockquote>\n\n\n\n<p><strong>Art\u00edculo 118. Sanciones.<\/strong> Las sanciones disciplinarias aplicables a los fiscales o a las fiscales, y dem\u00e1s funcionarios o funcionarias del Ministerio P\u00fablico, seg\u00fan la gravedad de las faltas cometidas son:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>1.- Apercibimiento.<\/p><p>2.- Amonestaci\u00f3n oral.<\/p><p>3.- Amonestaci\u00f3n escrita.<\/p><p>4.- Suspensi\u00f3n hasta por tres meses del ejercicio de las funciones y del goce del sueldo correspondiente.<\/p><p>5.- Destituci\u00f3n.<\/p><\/blockquote>\n\n\n\n<p>En el caso de que el o la Fiscal o el funcionario o la funcionaria haya incurrido en la causal n\u00famero cinco de esta Ley, se le aplicara exclusivamente esta \u00faltima sanci\u00f3n y no se le permitir\u00e1, bajo ninguna circunstancia, su reingreso al Ministerio P\u00fablico, sin perjuicio del inicio del juicio a que haya lugar. Asimismo, se le aplicar\u00e1 una multa igual al doble de la cantidad en la que se haya lucrado al incurrir en la mencionada causal o, en caso de no poder precisar con exactitud dicha cifra, la multa oscilar\u00e1 entre quinientas unidades tributarias (500 U.T.) y tres mil unidades tributarias (3.000 U.T.).<\/p>\n\n\n\n<p>La sanci\u00f3n disciplinaria se impondr\u00e1 mediante procedimiento que se regir\u00e1 por lo establecido en el Estatuto de Personal del Ministerio P\u00fablico. Para su imposici\u00f3n deber\u00e1n tomarse en cuenta los antecedentes del funcionario o funcionaria, as\u00ed como la debida proporcionalidad que debe existir entre la falta cometida y la sanci\u00f3n a ser aplicada.<\/p>\n\n\n\n<p><strong>Art\u00edculo 119. Del procedimiento.<\/strong> Para la imposici\u00f3n de la sanci\u00f3n, el Fiscal o la Fiscal Superior de la respectiva circunscripci\u00f3n judicial, a solicitud del Fiscal afectado, deber\u00e1 iniciar un procedimiento sancionatorio mediante auto de apertura, notific\u00e1ndole al funcionario o la funcionaria o al particular sobre la falta cometida. El investigado o investigada tendr\u00e1 la posibilidad de presentar un escrito de defensa de la falta que se le imputa, dentro de las cuarenta y ocho horas siguientes a la notificaci\u00f3n de inicio del procedimiento sancionatorio, con las pruebas que estime pertinentes. El Fiscal o la Fiscal Superior del Ministerio P\u00fablico decidir\u00e1 dentro de las setenta y dos horas siguientes a la presentaci\u00f3n del escrito por el investigado o la investigada.<\/p>\n\n\n\n<p>Toda sanci\u00f3n se impondr\u00e1 por resoluci\u00f3n escrita, debidamente motivada y contendr\u00e1 indicaci\u00f3n expresa del recurso que corresponda, en los t\u00e9rminos y modalidades previstos en la Ley, El Fiscal o la Fiscal Superior deber\u00e1 remitir a la Direcci\u00f3n de Adscripci\u00f3n del Fiscal afectado, copia de toda sanci\u00f3n impuesta a los o las particulares o a las funcionarias o funcionarios.<\/p>\n\n\n\n<p><strong>T\u00edtulo IX<br>Del Archivo y Manejo de la Documentaci\u00f3n<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 120. Confidencialidad.<\/strong> El archivo del Despacho del Fiscal o la Fiscal General de la Rep\u00fablica y el de las oficinas de los o las fiscales, as\u00ed como de cualquier otra dependencia del Ministerio P\u00fablico, es por su naturaleza privado y reservado para el servicio oficial, sin menoscabo del cumplimiento de los art\u00edculos 51 y 143 de la <a href=\"crbv.htm\">Constituci\u00f3n de la Rep\u00fablica Bolivariana de Venezuela<\/a> y del art\u00edculo 67 de la <a href=\"lodpublica.htm\">Ley Org\u00e1nica de la Defensor\u00eda del Pueblo<\/a>.<\/p>\n\n\n\n<p>El Fiscal o la Fiscal General de la Rep\u00fablica, mediante resoluci\u00f3n, determinar\u00e1 las condiciones de acceso al archivo y el uso de sus documentos.<\/p>\n\n\n\n<p><strong>Art\u00edculo 121. Reserva.<\/strong> Las personas que presten servicio en el Ministerio P\u00fablico guardaran reserva sobre los asuntos que conozcan en raz\u00f3n de sus funciones. Se les proh\u00edbe conservar para si o para terceros, tomar, sustraer o publicar copias de papeles, documentos o expedientes de archivo de los despachos respectivos.<\/p>\n\n\n\n<p><strong>Art\u00edculo 122.<\/strong> Certificaci\u00f3n. Una vez calificada la no confidencialidad del archivo fiscal, el Fiscal o la Fiscal autorizado, o el funcionario o funcionaria delegado para tal fin, certificara en el t\u00e9rmino de 15 d\u00edas continuos los instrumentos solicitados por autoridades o particulares que as\u00ed lo requieran.<\/p>\n\n\n\n<p><strong>Art\u00edculo 123. Devoluci\u00f3n de Documentos.<\/strong> Quienes presenten documentos originales ante el Despacho del Fiscal o la Fiscal General de la Rep\u00fablica tienen derecho a su devoluci\u00f3n, previa certificaci\u00f3n en el expediente respectivo, salvo que sea necesaria su presentaci\u00f3n en un proceso penal.<\/p>\n\n\n\n<p>La persona que presente una petici\u00f3n o solicitud tendr\u00e1 derecho a que se le expida copia certificada de ella, de los documentos acompa\u00f1ados y de la providencia reca\u00edda; pero no de los informes, opiniones y exposiciones de los funcionarios o funcionarias u organismos intervinientes en la tramitaci\u00f3n ni de los documentos agregados por el Despacho del Fiscal o la Fiscal General de la Rep\u00fablica u otro despacho oficial.<\/p>\n\n\n\n<p><strong>Art\u00edculo 124. Prohibici\u00f3n.<\/strong> No se podr\u00e1 ordenar la exhibici\u00f3n o inspecci\u00f3n general del archivo del Despacho del Fiscal o la Fiscal General de la Rep\u00fablica o de las oficinas adscritas al Ministerio P\u00fablico. Podr\u00e1 acordarse judicialmente la copia, exhibici\u00f3n o inspecci\u00f3n de determinado documento, expediente, libro o registro que corresponda al archivo, y se ejecutar\u00e1 la providencia dictada, a menos que la ley disponga la reserva de dicha documentaci\u00f3n o as\u00ed lo determine el Fiscal o la Fiscal General de la Rep\u00fablica, mediante resoluci\u00f3n motivada.<\/p>\n\n\n\n<p><strong>Art\u00edculo 125. Sello.<\/strong> El sello del Fiscal o la Fiscal General de la Rep\u00fablica ser\u00e1 de forma el\u00edptica, vertical y tendr\u00e1 cincuenta mil\u00edmetros de di\u00e1metro mayor y cuarenta de di\u00e1metro menor, el Escudo de Armas de la Rep\u00fablica en el centro, y alrededor una inscripci\u00f3n que diga: en la parte superior \u00abRep\u00fablica Bolivariana de Venezuela\u00bb \u00abMinisterio P\u00fablico\u00bb y en la inferior \u00abFiscal General de la Rep\u00fablica\u00bb. El sello de los fiscales o las fiscales del Ministerio P\u00fablico ser\u00e1 circular, de cuarenta mil\u00edmetros de di\u00e1metro, con las siguientes inscripciones: en la parte inferior en forma tambi\u00e9n circular y superpuestas: \u00abRep\u00fablica Bolivariana de Venezuela\u00bb \u00abMinisterio P\u00fablico\u00bb y en la parte interior alrededor del escudo, \u00abCircunscripci\u00f3n de\u00bb (aqu\u00ed el nombre de la Circunscripci\u00f3n Judicial) \u00abFiscal\u00bb (aqu\u00ed el n\u00famero).<\/p>\n\n\n\n<p><strong>Disposici\u00f3n Derogatoria<\/strong><\/p>\n\n\n\n<p><strong>\u00danica:<\/strong> Se deroga la Ley Org\u00e1nica del Ministerio P\u00fablico, publicada en la Gaceta Oficial N\u00b0 5.262 Extraordinario de la Rep\u00fablica de Venezuela de fecha 11 de septiembre de 1993 y todas las disposiciones que contrar\u00eden esta ley.<\/p>\n\n\n\n<p><strong>Disposici\u00f3n Transitoria<\/strong><\/p>\n\n\n\n<p><strong>\u00danica:<\/strong> El concurso para los cargos de Fiscal del Ministerio P\u00fablico se deber\u00e1 celebrar en un plazo no mayor de un a\u00f1o, contado a partir de la entrada en vigencia de esta Ley.<\/p>\n\n\n\n<p><strong>Disposici\u00f3n Final<\/strong><\/p>\n\n\n\n<p><strong>\u00danica:<\/strong> Esta Ley entrar\u00e1 en vigencia a partir de su publicaci\u00f3n en la Gaceta Oficial de la Rep\u00fablica Bolivariana de Venezuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo IDisposiciones Generales Cap\u00edtulo IObjeto de la Ley y Naturaleza Jur\u00eddica del Ministerio P\u00fablico Art\u00edculo 1. Objeto de la Ley. La presente Ley tiene por objeto regular la organizaci\u00f3n administrativa y funcional del Ministerio P\u00fablico. Art\u00edculo 2. Naturaleza jur\u00eddica del Ministerio P\u00fablico. El Ministerio P\u00fablico es un \u00f3rgano del Poder Ciudadano que tiene por objetivo &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"http:\/\/he.legal\/he\/ley-organica-del-ministerio-publico\/\"> <span class=\"screen-reader-text\">LEY ORG\u00c1NICA DEL MINISTERIO P\u00daBLICO<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leyes"],"_links":{"self":[{"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":1,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":503,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/posts\/501\/revisions\/503"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/media\/502"}],"wp:attachment":[{"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/he.legal\/he\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}